{"id":484,"date":"2007-11-24T12:46:34","date_gmt":"2007-11-24T10:46:34","guid":{"rendered":"http:\/\/www.oezratty.net\/wordpress\/2007\/abcdaire-des-conflits-sociaux\/"},"modified":"2008-03-29T18:08:20","modified_gmt":"2008-03-29T16:08:20","slug":"abcdaire-des-conflits-sociaux","status":"publish","type":"post","link":"https:\/\/www.oezratty.net\/wordpress\/2007\/abcdaire-des-conflits-sociaux\/","title":{"rendered":"Ab&eacute;c&eacute;daire des conflits sociaux"},"content":{"rendered":"<p>Je sors un peu de la ligne \u00e9ditoriale de ce blog en traitant de l&#8217;actualit\u00e9 sociale.<\/p>\n<p>Dans la ligne de &#8220;l&#8217;ABC\u00e9daire mal pensant&#8221; de JFK (pas le Pr\u00e9sident, le journaliste<a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/livre-jfk3.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; padding: 15px 0px 10px 15px; border-left: 0px; border-bottom: 0px\" height=\"244\" alt=\"Livre JFK\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/livre-jfk3-thumb.jpg\" width=\"145\" align=\"right\" border=\"0\"><\/a> chauve qui ne s&#8217;est pas trop foul\u00e9 dans cette livraison), voici donc un tout petit ABC\u00e9daire des conflits en cours et quelques avis sur la question. Surtout, pour mettre en \u00e9vidence le sens d\u00e9vi\u00e9 donn\u00e9 \u00e0 des termes courants de la vie \u00e9conomie. C&#8217;est la compilation de petites notes prises ces derni\u00e8res semaines.<\/p>\n<p>Et en plus, c&#8217;est gratuit&#8230;<\/p>\n<p><strong>Chirac<\/strong><\/p>\n<p>Jacques Chirac l&#8217;a \u00e9chapp\u00e9 belle pour l&#8217;instant. En effet, la justice vient de le mettre en examen pour semble-t-il, le moindre des m\u00e9faits dont il est \u00e0 l&#8217;origine. Les autres &#8211; fort nombreux &#8211; sont bien cach\u00e9s&#8230; dans les dossiers du Tribunal de Nanterre qui consolide les affaires Chirac. A moins que tout ce qui se raconte dans les &#8220;milieux renseign\u00e9s&#8221; ne soit que pure affabulation. Mais dans quelques temps, par exemple, l&#8217;appartement &#8220;pr\u00eat\u00e9&#8221; par la famille Hariri repr\u00e9sentera un cadeau en nature aussi important que les vacances de Sarkozy aux USA ou sa ballade dans le yacht de Bollor\u00e9. Mais bon, \u00e7a ferait vraiment d\u00e9sordre de d\u00e9baller tout ce linge vraiment tr\u00e8s sale. La situation de Chirac me rappelle un peu celle du h\u00e9ros du film Matchpoint de Woody Allen&#8230; il risque tr\u00e8s gros, mais pourrait en r\u00e9chapper compl\u00e8tement par miracle.<\/p>\n<p>La mise en examen de Jacques Chirac fait penser \u00e0 une vengeance froide de Sarkozy, mais les proc\u00e9dures judiciaires avaient d\u00e9marr\u00e9 il y a bien fort longtemps. C&#8217;est le retour \u00e0 la vie civile de Chirac qui a permis que la justice reprenne son chemin normal. D&#8217;un c\u00f4t\u00e9, cela fait d\u00e9sordre de voir ainsi le premier ancien Pr\u00e9sident de la R\u00e9publique mis en examen. Mais de l&#8217;autre, cela montre que tous les citoyens sont justiciables sans exception. Il reste \u00e0 voir comment va se terminer cette histoire.<\/p>\n<p>Rien \u00e0 voir avec les conflits sociaux, mais il est premier dans l&#8217;ordre alphab\u00e9tique.<\/p>\n<p><strong>Ch\u00f4mage<\/strong><\/p>\n<p><em>&#8220;Si on part plus tard en retraite, cela va augmenter le ch\u00f4mage&#8221; &#8230; <\/em>entendu chez les protecteurs des r\u00e9gimes sp\u00e9ciaux, voire dans la fonction publique. C&#8217;est peut-\u00eatre vrai dans le priv\u00e9 mais il en va autrement dans le secteur public. En effet, comme ce sont les imp\u00f4ts qui payent les salaires, il vaut mieux payer des gens qui produisent du travail que des retrait\u00e9s. Cela augmente le travail fourni par euro d&#8217;imp\u00f4ts pay\u00e9s. Comme on sait que la pression fiscale est trop lourde en France pour son \u00e9conomie, comparativement \u00e0 plein d&#8217;autres pays, faire travailler plus longtemps les r\u00e9gimes sp\u00e9ciaux (c&#8217;est-\u00e0-dire, au moins comme dans le priv\u00e9) ne peut qu&#8217;avoir un effet b\u00e9n\u00e9fique pour l&#8217;\u00e9conomie. Seul inconv\u00e9nient mais de taille: cela r\u00e9duit la capacit\u00e9 \u00e0 \u00e9quilibrer par les jeunes la pyramide des \u00e2ges dans le public. La moyenne d&#8217;\u00e2ge des travailleurs dans le public est d&#8217;environ 10 ann\u00e9es de plus que dans le priv\u00e9! Et cela risque d&#8217;empirer avec tous ces retrait\u00e9s qui ne seront pas remplac\u00e9s. En m\u00eame temps, si cela renforce les talents dans le priv\u00e9, pourquoi pas.<\/p>\n<p>Mais le transfert des emplois du public vers la production de richesses dans le priv\u00e9 ne peut pas se faire brutalement. Les comp\u00e9tences doivent \u00e9voluer, tout comme les mentalit\u00e9s. Et cela peut prendre quelques d\u00e9cennies, \u00e0 supposer que le mouvement soit r\u00e9ellement enclench\u00e9. D&#8217;o\u00f9 l&#8217;int\u00e9r\u00eat de proc\u00e9der plut\u00f4t par le non remplacement des agents du public qui partent \u00e0 la retraite plut\u00f4t que de supprimer directement des emplois.<\/p>\n<p><strong>Communication<\/strong><\/p>\n<p>Par les temps de crise et de revendications qui courent, on entend dire tout et son contraire et les d\u00e9bats sont rarement rationnels. Et surtout, il est tr\u00e8s difficile de se faire une id\u00e9e juste des donn\u00e9es du probl\u00e8me. Le conflit des r\u00e9gimes sp\u00e9ciaux en est un bon exemple. Les parties s&#8217;envoient argument et contre-arguments, et personne n&#8217;a expliqu\u00e9 pos\u00e9ment la donne en la vulgarisant avec des donn\u00e9es impartiales.<\/p>\n<p>Les grands m\u00e9dias se gargarisent plus des soubresauts des gr\u00e8ves et des n\u00e9gociations que du fond.&nbsp; Le gouvernement fait de son c\u00f4t\u00e9 preuve d&#8217;un manque incompr\u00e9hensible de p\u00e9dagogie. O\u00f9 est expliqu\u00e9e au quidam la r\u00e9forme des r\u00e9gimes sp\u00e9ciaux? Sur le <a href=\"http:\/\/www.travail-solidarite.gouv.fr\/espaces\/social\/793.html\">site du Minist\u00e8re du Travail<\/a>, pas un document de visible en home page qui l&#8217;explique! Et on dispose d&#8217;un bien maigrichonne page sur le <a href=\"http:\/\/www.premier-ministre.gouv.fr\/chantiers\/retraites_867\/\">site du Premier Ministre<\/a>. Quand au site de l&#8217;UMP, cens\u00e9 d\u00e9fendre la politique du gouvernement, il se contente en page&nbsp; d&#8217;accueil d&#8217;appeler \u00e0 la signature d&#8217;une p\u00e9tition pour r\u00e9former la France, sans force d\u00e9tails ni argumentaires. M\u00eame chose sur le site de la Justice et sur celui de l&#8217;Enseignement Sup\u00e9rieur. Incroyable! Est-ce la fin de la communication \u00e9crite? O\u00f9 sont pass\u00e9s les communicants? Que fait le service d&#8217;information du gouvernement? Qui va vulgariser l&#8217;\u00e9quilibre \u00e9conomique des r\u00e9gimes de retraite et d\u00e9tailler le co\u00fbt des r\u00e9gimes sp\u00e9ciaux par rapport \u00e0 celui du r\u00e9gime g\u00e9n\u00e9ral? Qui peut expliquer les r\u00e9formes de l&#8217;universit\u00e9, de la justice? Les Minist\u00e8res pourraient tout de m\u00eame se donner la peine d&#8217;\u00e9crire des &#8220;livres blancs&#8221; pour faire le marketing de leurs r\u00e9formes!<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image30.png\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"295\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb28.png\" width=\"433\" border=\"0\"><\/a> <\/p>\n<p>Le seul endroit sur le web o\u00f9 l&#8217;on peut en savoir plus sur toutes ces r\u00e9formes qui g\u00e9n\u00e8rent tant d&#8217;opposition, c&#8217;est le site de l&#8217;Assembl\u00e9e Nationale qui expose les projets de loi, d&#8217;amendements, et les discussions des commissions. Mais sans le travail de vulgarisation permettant \u00e0 ces informations de toucher un public large. Et s&#8217;il s&#8217;agit bien de lois, car pour les r\u00e9gimes sp\u00e9ciaux de retraite, si <a href=\"http:\/\/www.assemblee-nationale.fr\/13\/cra\/2007-2008\/003.asp#p25_234\">l&#8217;assembl\u00e9e en parle<\/a>, il ne s&#8217;agit pas de loi mais de d\u00e9crets pas encore publics. Le Ministre du travail Xavier Bertrand nous renvoie dans ses interventions, tout comme les syndicats, au <a href=\"http:\/\/www.cor-retraites.fr\/IMG\/pdf\/doc-723.pdf\">rapport du Conseil d&#8217;orientation des retraites<\/a> datant de janvier 2007. Soient 211 pages \u00e0 se farcir pour comprendre la situation! Et encore.<\/p>\n<p>On peut se demander si la communication du gouvernement est une forme d&#8217;incomp\u00e9tence ou bien un exercice de machiav\u00e9lisme. C&#8217;est peut-\u00eatre les deux \u00e0 la fois, le dernier \u00e9tant \u00e0 l&#8217;Elys\u00e9e, et la premi\u00e8re dans les Minist\u00e8res. Cela rel\u00e8ve aussi d&#8217;une incapacit\u00e9 \u00e0 ex\u00e9cuter rapidement. L&#8217;Elys\u00e9e bouscule le rythme s\u00e9rieusement au niveau des Minist\u00e8res et de leurs administrations centrales qui ne sont pas forc\u00e9ment habitu\u00e9es \u00e0 une telle vitesse d&#8217;ex\u00e9cution.<\/p>\n<p>En mati\u00e8re de communication, c&#8217;est aussi et surtout dans des symboles douteux &#8211; \u00e0 rebrousse poil de l&#8217;opinion &#8211; que le pouvoir surprend le plus. La loi TEPA qui co\u00fbte 15 milliards alors qu&#8217;il y a 40 milliards de d\u00e9ficit budg\u00e9taire, l&#8217;augmentation du Pr\u00e9sident (qui aurait pu \u00eatre mieux expliqu\u00e9e car il semble qu&#8217;il prenne maintenant en charges des frais qui ne l&#8217;\u00e9taient pas auparavant&#8230; mais combien au juste?), le yacht \u00e0 Malte, le Fouquet&#8217;s, les vacances aux USA. Bon, au moins, notre Pr\u00e9sident est effectivement transparent. Ce que d&#8217;autres cachaient par honte, il le montre par vantardise ou je ne sais quelle volont\u00e9 de d\u00e9complexion. Il \u00e9quilibre cela avec une mise en route rapide des nombreux chantiers qu&#8217;ils avait promis pendant la campagne \u00e9lectorale. Mais ceci ne justifie pas cela.<\/p>\n<p><strong>Cotisations<\/strong><\/p>\n<p>Selon un tract de gr\u00e9vistes de la SNCF ramass\u00e9 dans un TGV r\u00e9cemment &#8220;<em>les cotisations sociales des r\u00e9gimes sp\u00e9ciaux financent les b\u00e9n\u00e9fices compl\u00e9mentaires<\/em>&#8220;. Le r\u00e9gime g\u00e9n\u00e9ral cotise 6,75% de part salariale et 9,9% de part patronale, soit un total de 16,65%. Alors que le r\u00e9gime des cheminots cotise 7,85% de part salariale et 33,94% de part patronale, soit un total de 41,79%. Et les syndicats de faire un total de cotisations vieillesse de 159 840 \u20ac sur 40 ans dans le r\u00e9gime g\u00e9n\u00e9ral et de 376 110 \u20ac pour 37,5 ans de r\u00e9gime sp\u00e9cial. Oui mais&#8230; les cotisations, comme les salaires, sont pay\u00e9s par les usagers! <\/p>\n<p>Malgr\u00e9 ces cotisations, la SNCF affiche un <a href=\"http:\/\/www.entreprise-sncf.com\/mieux_nous\/RA2006\/SNCF-RF-2006.pdf\">bilan financier honorable<\/a> avec une marge nette de 6% en 2006, seule l&#8217;activit\u00e9 Fret \u00e9tant d\u00e9ficitaire, ce depuis de nombreuses ann\u00e9es. Elle re\u00e7oit certes quelques subventions, mais qui compensent des prestations fournies gratuitement \u00e0 certaines cat\u00e9gories d&#8217;usagers b\u00e9n\u00e9ficiaires. Par contre, sa dette a \u00e9t\u00e9 planqu\u00e9e dans le RFF qui g\u00e8re les infrastructures du r\u00e9seau ferr\u00e9. La RATP affiche pour sa part un bilan financier moins honorable et b\u00e9n\u00e9ficie de beaucoup plus de financements publics.<\/p>\n<p><strong>D\u00e9mocratie<\/strong><\/p>\n<p>Pour les \u00e9tudiants et autres gr\u00e9vistes en position de force, elle consiste \u00e0 faire voter par des assembl\u00e9es g\u00e9n\u00e9rales pas toujours bien repr\u00e9sentatives des d\u00e9cisions consistant \u00e0 priver d&#8217;autres personnes de leurs libert\u00e9s fondamentales: de circuler ou de travailler.<\/p>\n<p>D\u00e9sol\u00e9, ce n&#8217;est pas \u00e7a la d\u00e9mocratie! Ce sont des m\u00e9thodes de r\u00e9volutionnaires liberticides: le pouvoir aux soviets, le vote \u00e0 main lev\u00e9e, le pouvoir de la parole contre celui de la raison, une repr\u00e9sentativit\u00e9 contestable (avec des votants qui ne sont pas \u00e9l\u00e8ves dans l&#8217;universit\u00e9).<\/p>\n<p>La d\u00e9mocratie doit s&#8217;appuyer sur un socle de valeurs et de principes, que l&#8217;on trouve notamment dans les constitutions. Or la d\u00e9mocratie n&#8217;a pas pour objet de permettre aux uns de restreindre les libert\u00e9s fondamentales des autres. Si une moiti\u00e9 d&#8217;un pays votait pour lancer un g\u00e9nocide sur l&#8217;autre moiti\u00e9, cela ne serait \u00e9videmment pas la d\u00e9mocratie. Un blocage d&#8217;universit\u00e9 d\u00e9cid\u00e9 avec un vote \u00e0 bulletins secrets semble plus d\u00e9mocratique mais ne l&#8217;est pas pour autant.<\/p>\n<p>On ne peut pas voter n&#8217;importe quoi n&#8217;importe comment! C&#8217;est pour cela que les &#8220;blocages&#8221; &#8211; et non pas les gr\u00e8ves &#8211; sont hors la loi en France, et que les CRS interviennent dans les universit\u00e9s. Mais cette loi est loin d&#8217;\u00eatre respect\u00e9e partout. C&#8217;est pour cela que la situation en France laisse toujours songeur nos voisins \u00e9trangers.<\/p>\n<p><strong>D\u00e9tail<\/strong><\/p>\n<p>Banal mot souill\u00e9 par Jean-Marie Le Pen il y a d\u00e9j\u00e0 19 ans. Ce qui le rend inaudible dans tout discours politique depuis. Dommage car le mot est utile pour l&#8217;expression!<\/p>\n<p><strong>Dictature<\/strong><\/p>\n<p>La concentration des pouvoirs ex\u00e9cutifs de la R\u00e9publique \u00e0 Elys\u00e9e au d\u00e9triment de Matignon fait craindre \u00e0 certains l&#8217;irruption d&#8217;une dictature en France. Il ne faut pas pousser! Le bic\u00e9phalisme de l&#8217;ex\u00e9cutif en France est une exception mondiale. Dans la plupart des autres pays dits d\u00e9mocratiques, il n&#8217;y a qu&#8217;un seul ex\u00e9cutif. Quand il y a un Pr\u00e9sident ou un souverain, il n&#8217;a qu&#8217;un r\u00f4le honorifique (Allemagne, Italie, Isra\u00ebl, et Royaume Uni, Espagne, Danemark). Ces pays ont un r\u00e9gime plus parlementaire que celui de la France mais l&#8217;ex\u00e9cutif est unique et concentr\u00e9. Certes, le Pr\u00e9sident fran\u00e7ais concentre beaucoup de pouvoirs par rapport \u00e0 d&#8217;autres pays. Un r\u00e9\u00e9quilibrage des pouvoirs vers la repr\u00e9sentation nationale est bienvenue. Curieusement, ces \u00e9l\u00e9ments des propositions de la Commission Balladur sont pass\u00e9s sous silence par ceux qui la contestent.<\/p>\n<p>La France est plut\u00f4t une &#8220;polydictature&#8221;. Avec la dictature des syndicats et des corporations qui savent tr\u00e8s bien manipuler l&#8217;ex\u00e9cutif national ou local pour d\u00e9fendre leurs int\u00e9r\u00eats particuliers, trop souvent au d\u00e9triment de l&#8217;int\u00e9r\u00eat g\u00e9n\u00e9ral. Et la dictature des m\u00e9dias chauds qui simplifient \u00e0 outrance l&#8217;information.<\/p>\n<p>Qualifier la pr\u00e9sidence actuelle de dictature est faire injure aux pays qui vivent sous de r\u00e9elles dictatures. Toujours cette propension des fran\u00e7ais \u00e0 voir la partie \u00e0 moiti\u00e9 vide du verre&#8230;<\/p>\n<p><strong>EDF<\/strong><\/p>\n<p>Ils \u00e9taient plut\u00f4t discrets les gr\u00e9vistes de l&#8217;EDF ces derniers temps. Comme ils ne coupaient pas le courant, ils ne g\u00eanaient pas trop, donc on ne parlait que des agents de conduite des transports. Sont-ils discrets parce qu&#8217;ils prot\u00e8gent discr\u00e8tement quelques magots? Tel que leur fameux budget du comit\u00e9 d&#8217;entreprise (la CCAS) qui est index\u00e9 sur le chiffre d&#8217;affaire et non pas sur les salaires de l&#8217;entreprise. Le surco\u00fbt de cette in\u00e9galit\u00e9 de traitement entre salari\u00e9s est de plusieurs centaines de millions d&#8217;Euros. Soit largement le poids des concessions qui sont en train d&#8217;\u00eatre faites aux cheminots. Sans compter le fait que le magot servirait via quelques diverses magouilles \u00e0 financer indirectement la CGT et le PCF.<\/p>\n<p><strong>Egalit\u00e9<\/strong><\/p>\n<p>On veut bien \u00eatre \u00e9gaux avec tous les autres en France, pour peu qu&#8217;on ait plus qu&#8217;eux. Le pays du piston a beau jeu de promouvoir l&#8217;\u00e9galit\u00e9. <\/p>\n<p>Belle in\u00e9galit\u00e9 de fait, celle que les salari\u00e9s ont devant le sacro-saint droit de gr\u00e8ve. Les uns peuvent bloquer leur usine ou bureau sans que cela g\u00eane personne, et les autres peuvent bloquer un pays et lui faire perdre un demi-milliard d&#8217;Euros de PNB par jour de gr\u00e8ve. C&#8217;est \u00e7a l&#8217;\u00e9galit\u00e9? Ceux qui bloquent le pays ont invent\u00e9 le concept de gr\u00e8ve par procuration. Mais avec des revendications intenables comme le maintient des 37,5 ans de cotisation.<\/p>\n<p>On \u00e9voque aussi l&#8217;\u00e9galit\u00e9 des chances. Un vrai sujet r\u00e9publicain. On en est bien loin. Le racisme reste r\u00e9el en France et nuit gravement aux personnes dites pudiquement &#8220;de couleur&#8221;. Les \u00e9tudes sociologiques montrent aussi que les gros et les laids (selon les canons commun\u00e9ment admis) ont moins de chances de trouver du travail et d&#8217;\u00eatre promus dans leurs entreprises! Et les intelectuels fran\u00e7ais critiquent bien de la discrimination positive qui existe aux USA, en particulier dans les entreprises. Il n&#8217;emp\u00eache que la France n&#8217;est pas du tout exemplaire en mati\u00e8re de luttes contre les discriminations. La France de Dupont-Lajoie existe toujours, qu&#8217;on le veuille ou non. M\u00eame si elle est en costume cravatte.<\/p>\n<p>A propos d&#8217;\u00e9galit\u00e9, un petit pav\u00e9 dans la marre au passage (qui figurait dans mon doc sur le &#8220;Trop d&#8217;Etat&#8230;&#8221; tir\u00e9es de donn\u00e9es publi\u00e9es en 2006 par la Cour des Comptes dans son rapport sur les comptes de la s\u00e9curit\u00e9 sociale:<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image31.png\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"66\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb29.png\" width=\"394\" border=\"0\"><\/a> <\/p>\n<p>C&#8217;est curieux, personne n&#8217;a remarqu\u00e9 que les pensions dans le public \u00e9taient en moyenne du double de celles du priv\u00e9. Est-ce du fait du nombre d&#8217;enseignants? Il ne me semble pas que la r\u00e9partition cadres\/non cadres soit significativement diff\u00e9rente entre le public et le priv\u00e9&#8230; Cela m\u00e9rite d&#8217;\u00eatre creus\u00e9.<\/p>\n<p><strong>Entrepreneurs<\/strong><\/p>\n<p>Ce sont eux qui cr\u00e9ent richesses et emplois. Heureusement que quelques uns s&#8217;en occupent. Car dans le discours ambiant sur la croissance et le pouvoir d&#8217;achat, il y est rarement fait allusion. La commission Attali semble plancher sur le sujet, on attend rapidement ses conclusions et un plan d&#8217;action drastique pour changer la donne.<\/p>\n<p><strong>Equit\u00e9<\/strong><\/p>\n<p>Concept abstrait d\u00e8s lors qu&#8217;il s&#8217;agit de perdre quelque avantage que les autres n&#8217;ont pas. Concept encore plus abstrait lorsque l&#8217;on manque d&#8217;informations et de donn\u00e9es claires pour juger, ce qui fut le cas pendant la gr\u00e8ve qui vient de faire une pause. <\/p>\n<p><strong>Exigences<\/strong><\/p>\n<p>C&#8217;est la mani\u00e8re dont on n\u00e9gocie en France. La s\u00e9mantique des revendications indique clairement que nous ne sommes pas dans le pays du compromis et du gagnant-gagnant. Tout n&#8217;est que rapport de forces, pas de raison. C&#8217;est aga\u00e7ant pour le rationnaliste que je suis.<\/p>\n<p><strong>Emissions de carbone<\/strong><\/p>\n<p>Elles doivent battre des records en temps de gr\u00e8ve! Voici \u00e0 quoi ressemblaient les embouteillages \u00e0 Paris pendant la gr\u00e8ve (dans Sytadin) qui est maintenant &#8220;suspendue&#8221;:<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image32.png\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"342\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb30.png\" width=\"424\" border=\"0\"><\/a> <\/p>\n<p><strong>Fonds de pension<\/strong><\/p>\n<p>Ils ont bon dos les fonds de pension. Erreur des plus classiques r\u00e9p\u00e9t\u00e9e \u00e0 l&#8217;envie depuis plus d&#8217;un an par les politiques, tel ce Julien Dray qui dans &#8220;Esprit Libre&#8221; du vendredi 16 novembre rappelle que &#8220;<em>les fonds de pension sp\u00e9culent et veulent 15% de rentabilit\u00e9<\/em>&#8220;.<\/p>\n<p>Une confusion s\u00e9mantique permanente entre les fonds de pension (souvent anglo-saxons) et les fonds sp\u00e9culatifs, alors que :<\/p>\n<ul>\n<li>Les <strong>fonds de pension <\/strong>ont des rentabilit\u00e9s moyennes de 7% et financent les retraites priv\u00e9es dans les pays anglo-saxons, comme celle des fonctionnaires de l&#8217;Etat de Californie. Ils g\u00e8rent des placements \u00e0 risque mod\u00e9r\u00e9, pour assurer le versement des retraites. Leur panachage d&#8217;investissement peut les amener \u00e0 investir dans des fonds sp\u00e9culatifs, mais en faible proportion (moins de 15% environ).<\/li>\n<li>Les <strong>fonds sp\u00e9culatifs <\/strong>(hedge funds) qui eux g\u00e8rent de fonds \u00e0 risque, font des LBO et autres manipulations financi\u00e8res \u00e0 risque, et visent effectivement des rentabilit\u00e9s de 15%. <\/li>\n<\/ul>\n<p>Alors, regardons un peu les chiffres. Sur le site <a href=\"http:\/\/www.milliman.com\/pension_fund_survey\/pfs_index.php\">Milliman<\/a>, on y voit ce beau tableau sur les rendements des fonds de pension: <\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/clip-image001.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"92\" alt=\"clip_image001\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/clip-image001-thumb.jpg\" width=\"418\" border=\"0\"><\/a> <\/p>\n<p>Ils indiquent que les taux de rendement pr\u00e9vus par les fonds \u00e9taient en moyenne de 8 \u00e0 9%. Ce qui est d\u00e9j\u00e0 tr\u00e8s bien d\u2019ailleurs. Qu\u2019effectivement, il y a eu des taux tr\u00e8s \u00e9lev\u00e9s en 2003\/2004 : 19,4% et 12,4%, mais que cela faisait suite \u00e0 des taux n\u00e9gatifs sur deux ans, li\u00e9s \u00e0 la crise cons\u00e9cutive \u00e0 l\u2019\u00e9clatement de la bulle des technologies. Qu&#8217;enfin, les rendements de ces fonds d\u00e9pendent \u00e9troitement de la bourse plus que d&#8217;investissements priv\u00e9s (ceux qui sont g\u00e9r\u00e9s par les fonds \u00e0 risque). <\/p>\n<p>Les <a href=\"http:\/\/www.finfacts.com\/fincentre\/irishpenfunds.htm \">fonds de pension en Irlande<\/a> ont pr\u00e9sent\u00e9 de mani\u00e8re voisine un taux de rendement moyen de 14% sur 3 ans, mais de 7% sur 5 ans du fait des difficult\u00e9s du d\u00e9but des ann\u00e9es 2000, comme aux USA. Donc, impossible de g\u00e9n\u00e9rer 15% sur la dur\u00e9e pour un fond de pension! Par contre, les fonds de pension am\u00e9ricains ont d\u00e9plac\u00e9 une partie de leurs investissements vers l\u2019\u00e9tranger et notamment l\u2019Asie, qui offre des taux de croissances meilleurs. C\u2019est un des ph\u00e9nom\u00e8nes qui alimentent les d\u00e9localisations. <\/p>\n<p>Toute cette confusion s\u00e9mantique est \u00e0 la fois non voulue (<em>manque de culture \u00e9conomique<\/em>) et bien utile car elle d\u00e9cr\u00e9dibilise le principe des retraites compl\u00e9mentaires sous forme de fonds de pension. Je n&#8217;ai jamais vu un journaliste reprendre un politique qui faisait cette confusion.<\/p>\n<p><strong>Fragmentation<\/strong><\/p>\n<p>Parmi tous les maux qui affectent notre pays, il en est un qui est criant : l&#8217;extr\u00e8me fragmentation du pays \u00e0 tous les niveaux: administratif, l\u00e9gislatif, dans les TPE (pas assez de PME par rapport aux TPE). Elle g\u00e9n\u00e8re d\u00e9perditions, surco\u00fbts, inefficacit\u00e9s, et complexit\u00e9 tant pour les citoyens que pour les entreprises.<\/p>\n<p>On les trouve plus sp\u00e9cifiquement dans les domaines qui int\u00e9ressent le futur : dans <a href=\"https:\/\/www.oezratty.net\/wordpress\/2007\/grandes-ecoles-et-innovations\/\">l&#8217;enseignement sup\u00e9rieur<\/a>, dans les aides \u00e0 l&#8217;innovation et dans les p\u00f4les de comp\u00e9titivit\u00e9. J&#8217;avais \u00e9voqu\u00e9 ce point dans &#8220;<a href=\"https:\/\/www.oezratty.net\/wordpress\/2007\/trop-detat-o-a-bien-en-pdf\/\">Trop d&#8217;Etat, oui mais o\u00f9 \u00e7a?<\/a>&#8221; au printemps dernier. Il faut d\u00e9fragmenter ce pays qui est bien trop morcel\u00e9 autant verticalement (\u00e9tat, r\u00e9gion, d\u00e9partement, canton, communaut\u00e9 de communes, communes) qu&#8217;horizontalement (36000 communes). Cela ne veut pas dire qu&#8217;il faut tout centraliser et reconcentrer, mais revenir \u00e0 un \u00e9quilibre plus raisonnable pour faire des \u00e9conomies d&#8217;\u00e9chelle (au moins 5% de bureaucratie en moins).<\/p>\n<p>La d\u00e9fragmentation pose une question de m\u00e9thode car il faut la faire accepter par des d\u00e9cideurs &#8211; notamment \u00e9lus locaux &#8211; qui y seront naturellement oppos\u00e9s. Pourtant, on ne va pas passer en mode dictatorial pour imposer ces r\u00e9formes structurelles indispensables.<\/p>\n<p>Le gouvernement a d\u00e9j\u00e0 marqu\u00e9 des points avec la fusion RG\/DST, l&#8217;int\u00e9gration dans Oseo de l&#8217;Agence de l&#8217;Innovation Industrielle, avec Bercy (tr\u00e9sorerie et compta publique). Mais c&#8217;\u00e9tait au niveau national. Le plus facile \u00e0 faire!<\/p>\n<p>Rachida Dati a ensuite lanc\u00e9 un ballon sonde qui montre bien la difficult\u00e9 de proc\u00e9der \u00e0 cette d\u00e9fragmentation \u00e0 l&#8217;\u00e9chelle locale. La r\u00e9forme de la carte judiciaire et des tribunaux de prudhomme n&#8217;est que le d\u00e9but de ce qu&#8217;il faudrait faire pour d\u00e9fragmenter ce pays. Il faut du courage pour la mener car elle se heurte au protectionnisme des int\u00e9r\u00eats particuliers de chaque ville et r\u00e9gion.<\/p>\n<p>Bon courage pour la suite car il y a fort \u00e0 faire. <\/p>\n<p><strong>Honn\u00eatet\u00e9<\/strong><\/p>\n<p>Ca fait mal de voir que dans une enqu\u00eate r\u00e9cente (que je ne retrouve plus), les fran\u00e7ais apparaissent comme les moins honn\u00eates d&#8217;un panel de pays \u00e9tudi\u00e9s.<\/p>\n<p><strong>Managers<\/strong><\/p>\n<p>On n&#8217;en parle pas beaucoup, mais ne sont-ils pas aussi responsables lorsque des entreprises font faillite, licencient, d\u00e9localisent \u00e0 outrance? Les fonds am\u00e9ricains ont bon dos. Pourquoi tant de managers et leaders se trompent, n&#8217;innovent pas assez, ne prennent pas assez de risque? Probl\u00e8me de culture et d&#8217;\u00e9ducation sans doutes. L&#8217;atmosph\u00e8re anxiog\u00e8ne de la France ne pousse pas \u00e0 prendre des risques.<\/p>\n<p>Dans de nombreuses affaires r\u00e9centes (Airbus, etc), on confond aussi souvent d\u00e9lit d&#8217;initi\u00e9, malhonn\u00eatet\u00e9 et incomp\u00e9tence. La derni\u00e8re est bien plus courante que les premiers et explique plein de situations tordues.<\/p>\n<p>La &#8220;culture&#8221; semblait \u00eatre un axe de travail de la Commission Attali pour relancer la croissance. C&#8217;est un aspect cl\u00e9 des r\u00e9formes \u00e0 lancer en France. Mais r\u00e9former la culture ne se d\u00e9cr\u00e8te pas, ni ne se l\u00e9gif\u00e8re!<\/p>\n<p><strong>P\u00e9nibilit\u00e9<\/strong><\/p>\n<p>C&#8217;est un sujet s\u00e9rieux et il est curieux que le gouvernement n&#8217;affiche pas une volont\u00e9 de la prendre en compte. Mais il est d\u00e9licat de mesurer la p\u00e9nibilit\u00e9, l&#8217;esp\u00e9rance de vie, et sur tous les m\u00e9tiers. La loi ne peut pas toujours s&#8217;appuyer sur des donn\u00e9es qui \u00e9voluent incessamment. L&#8217;\u00e9galit\u00e9 de traitement nivelle peut-\u00eatre trop, mais c&#8217;est souvent la moins mauvaise solution.<\/p>\n<p>Dans le cas des cheminots, la p\u00e9nibilit\u00e9 a bon dos car elle prot\u00e8ge discr\u00e8tement les salari\u00e9s de ces r\u00e9gimes sp\u00e9ciaux qui travaillent dans des bureaux ou des ateliers et pas dans des tunnels. Et le rapport du Conseil d&#8217;Orientation des Retraites va dans le sens contraire des affirmations sur la p\u00e9nibilit\u00e9 dans sa globalit\u00e9: ainsi l&#8217;esp\u00e9rance de vie des salari\u00e9s de la RATP est plut\u00f4t dans la fourchette haute, en tout cas bien sup\u00e9rieure \u00e0 celle du priv\u00e9e (\u00e0 droite dans le tableau ci-dessous, FPE = fonction publique d&#8217;\u00e9tat):<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image33.png\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"118\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb31.png\" width=\"394\" border=\"0\"><\/a> <\/p>\n<p>L&#8217;esp\u00e9rance de vie des cheminots est peut-\u00eatre plus faible, mais ils repr\u00e9sentent une minorit\u00e9 des salari\u00e9s de ces r\u00e9gimes sp\u00e9ciaux. Et que dire du stress des conducteurs de bus qui est bien sup\u00e9rieur \u00e0 celui des agents de conduite du RER, mais qui gagnent beaucoup moins?<\/p>\n<p><strong>P\u00e9trole<\/strong><\/p>\n<p>Avec son augmentation, sera-t-il pay\u00e9 par nos imp\u00f4ts pour ceux chez qui il p\u00e8se lourd dans le compte d&#8217;exploitation (marins-p\u00eacheurs, routiers, taxis, ambulanciers)? Ca m\u00e9rite r\u00e9flexion car on pourrait payer ce surcroit de deux mani\u00e8res: par l&#8217;augmentation des prix des produits et services affect\u00e9s, ou par nos imp\u00f4ts. L&#8217;un est li\u00e9 \u00e0 la consommation, l&#8217;autre \u00e0 la solidarit\u00e9 nationale. Quand il s&#8217;agit de business et pas de service public, pourquoi passerait-on par la solidarit\u00e9? Pour pousser le bouchon un peu loin, rappelons que les poissons de nos marins-p\u00eacheurs sont plut\u00f4t situ\u00e9s dans le haut de gamme et donc pour une client\u00e8le ais\u00e9e. Alors que les autres d\u00e9gustent du poisson d&#8217;\u00e9levage comme ces saumons de batterie de Norv\u00e8ge, et encore, c&#8217;est bien cher pour pas mal de fran\u00e7ais. Alors, la TVA des plus pauvres doit-elle financer des prix inf\u00e9rieurs \u00e0 ceux du march\u00e9 pour les familles plus ais\u00e9es?<\/p>\n<p>En tout cas, plus vite le p\u00e9trole sera cher, plus vite nous investirons dans des moyens alternatifs de production d&#8217;\u00e9nergie, aujourd&#8217;hui encore peu comp\u00e9titifs. J&#8217;aime bien notamment ce projet allemand d&#8217;utilisation de l&#8217;\u00e9nergie solaire au Sahara pour alimenter l&#8217;Europe en \u00e9lectricit\u00e9 (centrale thermique solaire ou photovolta\u00efque).<\/p>\n<p>Les solutions alternatives au p\u00e9trole existent pour la plupart des besoins. A une exception notable pr\u00e8s: l&#8217;aviation. Celle-ci a besoin de k\u00e9ros\u00e8ne, une essence l\u00e9g\u00e8re. Elle est plut\u00f4t difficile \u00e0 g\u00e9n\u00e9rer avec des ol\u00e9agineux (colza, etc), m\u00eame si on exp\u00e9rimente des k\u00e9ros\u00e8nes hybrides r\u00e9alis\u00e9s avec des algues marines. L&#8217;aviation va s\u00e9rieusement souffrir s\u00e9rieusement dans les quinze ann\u00e9es qui viennent!<\/p>\n<p><strong>Pouvoir d&#8217;achat<\/strong><\/p>\n<p>Promesse \u00e9lectorale impossible \u00e0 tenir \u00e0 court terme quand il s&#8217;agit de l&#8217;augmenter. Sarkozy a lanc\u00e9 un certain nombre d&#8217;actions qui auront peut-\u00eatre un impact \u00e0 moyen\/long terme, c&#8217;est bien. Il faut effectivement cr\u00e9er les conditions pour g\u00e9n\u00e9rer plus de richesses, pour exporter plus, pour produire plus avec moins. On peut aussi am\u00e9liorer la redistribution, mais attention, la France est probablement d\u00e9j\u00e0 le pays le plus redistributeur au monde. Et m\u00eame si la corr\u00e9lation est discutable, cela ne renforce pas son \u00e9conomie.<\/p>\n<p>Baisser les prix? Pourquoi pas, mais la France est d\u00e9j\u00e0 le pays le plus cheap d&#8217;Europe. On a des prix bas, mais aussi des salaires tr\u00e8s bas. Et les habitudes de consommation tirent l&#8217;\u00e9conomie vers le bas. Alors, enfoncer le clou&#8230;<\/p>\n<p><strong>Privil\u00e9gi\u00e9s<\/strong><\/p>\n<p>Le mot \u00e0 la mode&#8230;<\/p>\n<p>O\u00f9 l&#8217;on peut aussi facilement confondre privil\u00e8ge indu et meilleure situation explicable, ou position relative dans le revenu des fran\u00e7ais.<\/p>\n<p>La tactique classique de communication des syndicats consiste \u00e0 mettre en \u00e9vidence des in\u00e9galit\u00e9s verticales (qui existeront toujours, surtout si le point de r\u00e9f\u00e9rence sont les 100 plus riches de France ou les patrons qui gagnent plusieurs millions d&#8217;Euros par an) pour justifier les in\u00e9galit\u00e9s horizontales (qui concernent des centaines de milliers voire des millions de foyers). On appelle cela &#8220;botter en touche&#8221; en communication. Avec toujours cette id\u00e9e du grand soir consistant \u00e0 ponctionner chez les plus riches pour niveler par le haut les in\u00e9galit\u00e9s du bas. On sait que cela ne fonctionne pas car cela appauvrit toute \u00e9conomie qui s&#8217;y tenterait. Une bonne redistribution des richesses reste un fondement de la R\u00e9publique, mais elle doit tenir compte des r\u00e9alit\u00e9s \u00e9conomiques internationales, de la libert\u00e9 de mouvement des personnes et des capitaux.<\/p>\n<p>Dans toutes les civilisations et mod\u00e8les \u00e9conomiques de l&#8217;histoire de l&#8217;humanit\u00e9, il y a toujours eu mati\u00e8re \u00e0 trouver plus privil\u00e9gi\u00e9 que soi. La nature humaine la rend g\u00e9n\u00e9ralement toujours envieuse par rapport aux \u00e9tages &#8220;du dessus&#8221;. <\/p>\n<p>Les cheminots et la CGT et de Sud en sont un bon exemple: ils bottent en touche sur leurs avantages de r\u00e9gimes sp\u00e9ciaux en rappelant les stock options et les patrons qui s&#8217;en mettent plein les poches. Ils d\u00e9noncent la loi TEPA qui aurait dilapid\u00e9 15 milliards d&#8217;Euros qui auraient tr\u00e8s bien pu servir \u00e0 financer les retraites. Dans la veine &#8220;<em>il y a toujours plus riche que soi<\/em>&#8220;, on pouvait aussi voir et entendre No\u00ebl Forgeard dans &#8220;Contre enqu\u00eate&#8221; sur France 2, qui trouvait qu&#8217;il est un nain (salari\u00e9) c\u00f4t\u00e9 richesse par rapport \u00e0 Bernard Arnault (sans le nommer). Un comble de maladresse alors qu&#8217;il pr\u00e9sentait sa feuille d&#8217;imp\u00f4ts de 3 millions d&#8217;Euros!<\/p>\n<p>Parfois, certains se retrouvent \u00e0 jalouser leur propre situation avec un effet de boomerang inattendu. Il en va ainsi de la d\u00e9nonciation de la loi TEPA (le &#8220;paquet fiscal&#8221;) de juillet 2007. Les cheminots disent qu&#8217;ils ne sont pas des privil\u00e9gi\u00e9s. Mais ils le sont, tout du moins, par rapport \u00e0 ceux qui gagnent moins pour un effort \u00e9quivalent. Ainsi, un foyer de cheminot en milieu\/fin de carri\u00e8re gagne plus de 2500\u20ac de revenu par mois. Un conducteur de TGV gagne plus de 3000\u20ac en fin de carri\u00e8re primes comprises (<a href=\"http:\/\/www.entreprise-sncf.com\/communiq\/hoax2.htm\">source SNCF<\/a>). Pour les autres cheminots, les salaires s&#8217;\u00e9talent entre 1500\u20ac et 3000\u20ac par mois (net ou brut, je ne sais pas trop). Ce qui les place &#8211; en milieu et fin de carri\u00e8re &#8211; dans les foyers les 10% les plus ais\u00e9s en France selon l&#8217;INSEE! Pour m\u00e9moire, le salaire m\u00e9dian en France est de 1680\u20ac bruts (voir cette <a href=\"http:\/\/www.insee.fr\/fr\/ffc\/chifcle_fiche.asp?tab_id=505\">grille de salaires<\/a> de l&#8217;INSEE)! Ces niveaux de salaire ne sont pas pour autant forc\u00e9ment des privil\u00e8ges (qui sous-entendent&#8230; quelque chose d&#8217;indu). <\/p>\n<p>Quelques mesures contest\u00e9es de la loi TEPA concernent m\u00eame les cheminots. Telle cette exon\u00e9ration des droits de succession repouss\u00e9e de 50K\u20ac par b\u00e9n\u00e9ficiaire \u00e0 150K\u20ac. Qui en b\u00e9n\u00e9ficie? Essentiellement, les classes moyennes propri\u00e9taires de leur logement. Tels les deux enfants de ce cheminot qui s&#8217;est achet\u00e9 dans les ann\u00e9es 1970-1990 son pavillon de banlieue, qui vaut maintenant dans les 200-400K\u20ac et qu&#8217;il a pu rembourser car son emploi n&#8217;\u00e9tait pas menac\u00e9! Les enfants de ceux qui font aujourd&#8217;hui gr\u00e8ve! Jean-Fran\u00e7ois Kahn d\u00e9nonce dans un &#8220;Marianne&#8221; r\u00e9cent le fait que les droits de succession aient \u00e9t\u00e9 abolis&nbsp; &#8220;<em>ce qui permet la renaissance d&#8217;un ordre aristocratique<\/em>&#8220;. Si les cheminots sont des aristocrates pour Marianne, alors, va&#8230; Mais n&#8217;est pas aristocrate qui l&#8217;ont pense! Les patrimoines &#8216;aristocrate&#8217; qui d\u00e9passent 150K\u20ac par h\u00e9ritier paieront toujours des droits de succession. Sauf sur un point: l&#8217;exon\u00e9ration totale de droits de succession entre \u00e9poux qui n&#8217;a pas \u00e9t\u00e9 plafonn\u00e9e. Elle aurait pu l&#8217;\u00eatre, c&#8217;est vrai. La r\u00e9forme des droits de succession de la loi TEPA touche en fait le plus les 10% des foyers qui suivent les 10% les plus riches (dont le patrimoine est sup\u00e9rieur \u00e0 400K\u20ac). Et dans ce &#8220;second d\u00e9cile&#8221;, on trouve \u00e9norm\u00e9ment de foyers qui se sentent d\u00e9favoris\u00e9s mais qui ont une bonne situation par rapport \u00e0 la moyenne des fran\u00e7ais. Et donc, une forte proportion de b\u00e9n\u00e9ficiaires des r\u00e9gimes sp\u00e9ciaux s&#8217;y retrouvent! Je ne les en bl\u00e2me pas pour autant. Mais il est bon de remettre les choses \u00e0 leur place.<\/p>\n<p>Cette loi TEPA a en tout cas \u00e9t\u00e9 vot\u00e9e avec un bon timing : c&#8217;\u00e9tait en gros le seul moment o\u00f9 elle pouvait passer. Et puis, tout all\u00e8gement de la fiscalit\u00e9 directe touche d&#8217;abord les privil\u00e9gi\u00e9s puisque ce sont eux qui payent le plus d&#8217;imp\u00f4t directs. Fallait-il modifier la fiscalit\u00e9 indirecte (la TVA), ce qui serait plus &#8220;juste&#8221;? Pas facile car le pays a moins de marges de manoeuvre du fait de l&#8217;harmonisation europ\u00e9enne et de l&#8217;impact plus fort sur les recettes d&#8217;une baisse de la TVA.<\/p>\n<p><strong>Riches<\/strong><\/p>\n<p>Comme pour les &#8220;privil\u00e9gi\u00e9s&#8221;, ils se d\u00e9finissent g\u00e9n\u00e9ralement de mani\u00e8re autocentr\u00e9e comme \u00e9tant ceux qui ont plus que vous. Et r\u00e9ciproquement pour les pauvres.<\/p>\n<p>Cela s&#8217;applique \u00e9galement aux pays. On lit et entend rarement que la France est un pays riche! Ni qu&#8217;elle est pauvre. Alors qu&#8217;on est juste dans un milieu et en baisse constante&#8230;<\/p>\n<p><strong>Sciences humaines<\/strong><\/p>\n<p>D&#8217;o\u00f9 viennent les gr\u00e8ves \u00e9tudiantes? Principalement des facs de sciences humaines. Et cela, depuis 40 ans. O\u00f9 est la Fac d&#8217;Orsay? O\u00f9 est Paris VI? O\u00f9 sont les facs de science de Grenoble? Pas dans la gr\u00e8ve, et en tout cas, pas \u00e0 leur d\u00e9marrage. Par contre, pas de probl\u00e8me pour y trouver Tolbiac (sciences humaines, droit, gestion), Nanterre (sciences humaines, droit, gestion, sciences pour moins de 8% des \u00e9tudiants), Rennes (sciences humaines, droit, sant\u00e9, gestion), Rouen (sciences humaines, droit, sant\u00e9, sport, sciences dures pour moins de 20%), Nancy (sant\u00e9, sciences de l&#8217;ing\u00e9nieur pour 40%), Perpignan (sciences humaines, droit, gestion, 17% de sciences dures), Aix Marseille 1 (lettres et 1\/3 de sciences), Reims (sciences humaines, sant\u00e9, droit, gestion, environ 15% de sciences exactes) pour n&#8217;en citer que quelques unes.<\/p>\n<p>Ces \u00e9tudiants font de plus le pont avec les revendications du service public. Est-ce parce que leurs principales perspectives d&#8217;emploi sont dans ce secteur, notamment dans l&#8217;enseignement?<\/p>\n<p>Et ils n&#8217;y vont pas de main morte. Point de n\u00e9gociation! Ils demandent purement et simplement l&#8217;abrogation sans conditions de la Loi P\u00e9cresse. Mais n&#8217;est pas Truman qui veut. Ce refus obstin\u00e9 de l&#8217;entreprise ou le d\u00e9pit du risque qu&#8217;elles ne s&#8217;int\u00e9ressent pas aux sciences molles est sid\u00e9rant. Il est vrai que les entreprises se tourneront un peu plus vers les business schools et les sciences dures car cela correspond \u00e0 leurs besoins. C&#8217;est une loi du march\u00e9 qui g\u00eane les \u00e9tudiants. En attendant, il est navrant de voir que d&#8217;un c\u00f4t\u00e9, on trouve des \u00e9tudiants en philo et autres sciences humaines qui ne trouvent pas de d\u00e9bouch\u00e9s sur le march\u00e9 du travail, et de l&#8217;autre, toutes ces boites qui recrutent ing\u00e9nieurs et informaticiens &#8211; <em>m\u00eame jeunes! <\/em>&#8211; et ne trouvent pas de recrues! Ce, d&#8217;autant plus que la France a l&#8217;un des plus forts taux d&#8217;\u00e9tudiants dans les sciences molles en Europe, et parait-il, 40% des \u00e9tudiants en psychologie de toute l&#8217;Europe (<em>cf ci-dessous<\/em>)!<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image34.png\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"235\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb32.png\" width=\"406\" border=\"0\"><\/a> <\/p>\n<p>La loi P\u00e9cresse ne va pourtant pas bien loin car une v\u00e9ritable r\u00e9forme de l&#8217;Universit\u00e9 aurait \u00e9t\u00e9 de mettre en place la s\u00e9lection et des droits d&#8217;entr\u00e9e afin, en amont, de r\u00e9duire le taux d&#8217;\u00e9chec qui nuit aux \u00e9tudiants eux-m\u00eames. Avec moins d&#8217;\u00e9checs, les \u00e9tudiants auraient plus de moyens dans leurs \u00e9tudes. Et les \u00e9tudiants seraient r\u00e9orient\u00e9s vers des fili\u00e8res plus porteuses, plus qualifiantes, m\u00eame si plus &#8220;professionnalisantes&#8221; (bah quelle horreur, de la chair \u00e0 exploitation pour les entreprises). Mais aujourd&#8217;hui, il vaut mieux \u00eatre BAC+3 en sciences dures ou en technologie que BAC+5 en sciences molles!<\/p>\n<p>Le comble c&#8217;est que nous avons l\u00e0 une gr\u00e8ve provoqu\u00e9e par la crainte de mesures qui n&#8217;ont justement pas \u00e9t\u00e9 int\u00e9gr\u00e9es dans la loi P\u00e9cresse par crainte&#8230; de gr\u00e8ves des \u00e9tudiants!<\/p>\n<p><strong>S\u00e9lection<\/strong><\/p>\n<p>Intervient toujours \u00e0 un moment o\u00f9 \u00e0 un autre, n&#8217;en d\u00e9plaise aux tenants d&#8217;une \u00e9galit\u00e9 \u00e0 tout crin. Notre syst\u00e8me \u00e9ducatif et d&#8217;emploi est s\u00e9lectif \u00e0 tous les niveaux. Mais un \u00e9quilibre de la s\u00e9lection est n\u00e9cessaire. Il vaut mieux l&#8217;\u00e9taler dans tout le cycle plut\u00f4t que de la tasser \u00e0 BAC+2, l\u00e0 o\u00f9 par exemple il y a \u00e9norm\u00e9ment d&#8217;\u00e9checs dans les universit\u00e9s en plein milieu de cursus, o\u00f9 bien \u00e0 la fin du cycle, dans des concours administratifs pour entrer dans la fonction publique.<\/p>\n<p><strong>Vel Satis<\/strong><\/p>\n<p>C&#8217;est la voiture (avec chauffeur) de Bernard Thibault, le secr\u00e9taire g\u00e9n\u00e9ral de la CGT. Ca fait Ministre, et moins modeste que la Laguna II choisie par S\u00e9gol\u00e8ne Royal en remplacement, justement, d&#8217;une Vel Satis trop voyante. Il ne faut pas s&#8217;\u00e9tonner si la base s&#8217;\u00e9loigne de la t\u00eate dans certains syndicats! L\u00e0 aussi, la valeur des symboles n&#8217;est pas bien comprise.<\/p>\n<p>================<\/p>\n<p>Bon, aller, c&#8217;\u00e9tait pour se d\u00e9fouler apr\u00e8s ces deux semaines agit\u00e9es.<\/p>\n<p>Comme citoyen, j&#8217;appr\u00e9cierai en tout cas d&#8217;\u00eatre mieux inform\u00e9 sur les r\u00e9formes qui sont en cours. Et que les d\u00e9bats soient un peu plus pos\u00e9s et rationnels, avec \u00e9l\u00e9ments concrets pour se forger une opinion. Sinon, c&#8217;est la dictature de la communication par m\u00e9dias chauds interpos\u00e9s.<\/p>\n<p>La prochaine semaine, je suis \u00e0 San Francisco dans le <a href=\"http:\/\/techiteasy.org\/study-trip-to-silicon-valley\/\">voyage d&#8217;\u00e9tude<\/a> organis\u00e9 par J\u00e9r\u00e9my Fain. L&#8217;occasion de prendre un beau bol d&#8217;air frais et d&#8217;optimisme, \u00e0 la d\u00e9couverte de la Silicon Valley et du miracle de l&#8217;entrepreneuriat qui n&#8217;y a pas pris une ride. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je sors un peu de la ligne \u00e9ditoriale de ce blog en traitant de l&#8217;actualit\u00e9 sociale. Dans la ligne de &#8220;l&#8217;ABC\u00e9daire mal pensant&#8221; de JFK (pas le Pr\u00e9sident, le journaliste chauve qui ne s&#8217;est pas trop foul\u00e9 dans cette livraison), voici donc un tout petit ABC\u00e9daire des conflits en cours et quelques avis sur la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,13,17,34,11,12,18,25],"tags":[],"class_list":["post-484","post","type-post","status-publish","format-standard","hentry","category-actualites","category-communication","category-economie","category-enseignement-superieur","category-france","category-management","category-politique","category-sociologie"],"views":13775,"_links":{"self":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/comments?post=484"}],"version-history":[{"count":0,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts\/484\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/media?parent=484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/categories?post=484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/tags?post=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}