{"id":421,"date":"2007-10-02T23:56:23","date_gmt":"2007-10-02T21:56:23","guid":{"rendered":"http:\/\/www.oezratty.net\/wordpress\/2007\/illusions-de-la-commission-europenne-sur-microsoft\/"},"modified":"2007-10-02T23:56:25","modified_gmt":"2007-10-02T21:56:25","slug":"illusions-de-la-commission-europenne-sur-microsoft","status":"publish","type":"post","link":"https:\/\/www.oezratty.net\/wordpress\/2007\/illusions-de-la-commission-europenne-sur-microsoft\/","title":{"rendered":"Illusions de la Commission Europ&eacute;enne sur Microsoft"},"content":{"rendered":"<p>L&#8217;<a href=\"http:\/\/curia.europa.eu\/jurisp\/cgi-bin\/form.pl?lang=FR&amp;Submit=Rechercher$docrequire=alldocs&amp;numaff=T-201\/04&amp;datefs=&amp;datefe=&amp;nomusuel=&amp;domaine=&amp;mots=&amp;resmax=100\">Arr\u00eat du Tribunal de Premi\u00e8re Instance<\/a> de la Cour Europ\u00e9enne de Justice rendu il y a deux semaines \u00e9tant un peu derri\u00e8re nous, penchons nous avec un peu de recul sur l&#8217;impact de ce document de&nbsp;244 pages bien denses qui reprennent les arguments des deux parties et tranchent en faveur de la Commission sauf sur un d\u00e9tail de forme.<\/p>\n<p>La premi\u00e8re cour de justice pouvant \u00eatre sollicit\u00e9e par Microsoft dans cette affaire a donc maintenu les sanctions impos\u00e9es par la Commission Europ\u00e9enne. Elles se r\u00e9sument \u00e0 l&#8217;obligation de proposer aux clients (constructeurs pour l&#8217;essentiel) une version de Windows sans Windows Media Player, et de fournir aux concurrents de Microsoft toute la documentation n\u00e9cessaire relative aux protocoles liant Windows et Windows Server, permettant en gros de cloner ce dernier. Les ambig\u00fcit\u00e9s sur le &#8220;toute&#8221; ayant d\u00e9j\u00e0 co\u00fbt\u00e9 \u00e0 Microsoft la bagatelle de 280m\u20ac d&#8217;amendes!<\/p>\n<p>Mais au juste, est-ce que cela a un r\u00e9el impact sur la position de Microsoft sur le march\u00e9 des syst\u00e8mes d&#8217;exploitation? Rien n&#8217;est moins s\u00fbr! Est-ce que cela a un impact sur Microsoft tout court? Oui, mais pas l\u00e0 o\u00f9 on l&#8217;imagine forc\u00e9ment. Est-ce qu&#8217;il y aurait d&#8217;autres choses \u00e0 faire pour limiter la part de march\u00e9 de Windows? Pas vraiment.<\/p>\n<p>C&#8217;est ce que je vais explorer dans ce long post (<em>vous avez l&#8217;habitude&#8230; hein?<\/em>).<\/p>\n<p><strong>Les r\u00e9actions \u00e0 la d\u00e9cision du tribunal<\/strong><\/p>\n<p>On en trouvait de toutes sortes, qui allaient de l&#8217;optimisme b\u00e9at et presque irr\u00e9el \u00e0 des doutes marqu\u00e9s. Morceaux choisis et commentaires&#8230;&nbsp;<\/p>\n<blockquote>\n<p><em>\u00abC&#8217;\u00e9tait un grand jour pour les entreprises et les consommateurs europ\u00e9ens. A long terme, cette d\u00e9cision ouvre la possibilit\u00e9 d&#8217;une comp\u00e9tition dynamique dans l&#8217;industrie du logiciel. Il n&#8217;y aura plus d&#8217;utilisateurs captifs, plus de monopole des prix&nbsp;\u00bb, estime Thomas Vinje, le porte-parole du Comit\u00e9 europ\u00e9en pour l&#8217;interop\u00e9rabilit\u00e9 des syst\u00e8mes (ECIS). Une association dans laquelle figurent, entre autres, RealNetworks et Sun, deux des principaux protagonistes \u00e0 l&#8217;origine de cette saga judiciaire qui dure depuis neuf ans.<\/em>&#8221; (dans <a href=\"http:\/\/rss.01net.com\/www.01net.com\/article\/359209.html?r=\/rss\/actus.xml\">01Net<\/a>&nbsp;qui r\u00e9sume bien l&#8217;affaire par ailleurs)&nbsp;<\/p>\n<\/blockquote>\n<blockquote>\n<p>&#8220;<em>L&#8217;Union prot\u00e8ge efficacement contre les dangers de la mondialisation<\/em>&#8221; en mettant en oeuvre&nbsp;le &#8220;<em>droit contre la force<\/em>&#8220;.&nbsp;Rien que \u00e7a! Lu dans Le Monde du 28 septembre, sous la plume de Sylvie Goulard, pr\u00e9sidente du <a href=\"http:\/\/www.mouvement-europeen.org\/\">Mouvement Europ\u00e9en France<\/a> dans son papier &#8220;<a href=\"http:\/\/www.mouvement-europeen.org\/mefpresse\/pdf\/monde_27_09_07.pdf\">Microsoft ou l&#8217;Europe par la preuve<\/a>&#8220;.<\/p>\n<\/blockquote>\n<p>Mais les commentaires mitig\u00e9s \u00e9taient dans l&#8217;ensemble plus fournis:<\/p>\n<blockquote>\n<p>&#8220;<em>L&#8217;\u00e9diteur commercialise depuis la mi-2005 une version all\u00e9g\u00e9e de Windows, sans son lecteur multim\u00e9dia maison. Malgr\u00e9 tout, il y a fort \u00e0 parier que la concurrence n&#8217;en ait pas profit\u00e9. Les consommateurs pr\u00e9f\u00e8rent massivement se procurer la version coupl\u00e9e avec Windows Media Player, les deux packs \u00e9tant commercialis\u00e9s au m\u00eame tarif.<\/em>&#8221; (dans <a href=\"http:\/\/rss.01net.com\/www.01net.com\/article\/359209.html?r=\/rss\/actus.xml\">01Net<\/a>). A ceci pr\u00e8s que les constructeurs ont sagement pris cette d\u00e9cision pour les consommateurs, qui d&#8217;ailleurs, ne s&#8217;en soucient gu\u00e8re.<\/p>\n<\/blockquote>\n<blockquote>\n<p>&#8220;<em>Malgr\u00e9 sa condamnation par Bruxelles, Microsoft entend maintenir son h\u00e9g\u00e9monie<\/em>&#8221; (Le Monde du 19 septembre 2007) et d&#8217;ajouter: &#8220;<em>Compte tenu de l&#8217;h\u00e9g\u00e9monie commerciale de Microsoft, les amendes \u00e0 r\u00e9p\u00e9tition peuvent-elles avoir un r\u00f4le dissuasif ? La firme de Redmond use et abuse de recours et d&#8217;appels, puis d\u00e9pose sans sourciller les montants des amendes sur des comptes bloqu\u00e9s. Les mesures impos\u00e9es, comme la vente de Windows XP sans le M\u00e9dia Player, sont noy\u00e9es dans la masse des ventes de syst\u00e8mes d&#8217;exploitation Windows. Microsoft, par ses multiples proc\u00e9dures, gagne du temps et conforte progressivement sa position sur des march\u00e9s strat\u00e9giques.<\/em>&#8220;. Pas faux sur l&#8217;impact des mesures. Quand \u00e0 la strat\u00e9gie juridique de Microsoft ainsi d\u00e9nonc\u00e9e, elle est extr\u00eamement classique et respecte tout \u00e0 fait&nbsp;le droit.&nbsp;Faire appel fait partie des droits de n&#8217;importe quel accus\u00e9, et Microsoft aurait d&#8217;ailleurs certainement pr\u00e9f\u00e9r\u00e9 que la proc\u00e9dure aille plus vite! 6 ans d&#8217;instruction de la Commission et 3 ans pour l&#8217;appel, cela tape sur les nerfs!&nbsp;<\/p>\n<\/blockquote>\n<blockquote>\n<p>L&#8217;AFUL qui <a href=\"http:\/\/www.aful.org\/presse\/lettre-concurrence-vista\">d\u00e9nonce<\/a> des mesures au coup par coup de la Commission Europ\u00e9enne contre Microsoft en titrant &#8220;<em>Face \u00e0 Microsoft, la Commission Europ\u00e9enne organise son impuissance en ignorant les consommateurs<\/em>&#8220;. Et remet sur la table la question lancinante des bundles de Windows dans les PC des constructeurs. Tout en r\u00e9\u00e9crivant un peu l&#8217;histoire, mettant ainsi l&#8217;\u00e9chec de BeOS sur les pratiques anticoncurrentielles de Microsoft!<\/p>\n<\/blockquote>\n<blockquote>\n<p>C-NET avec &#8220;<a href=\"http:\/\/www.news.com\/8301-10784_3-9780402-7.html?part=rss&amp;subj=news&amp;tag=2547-1_3-0-20\">The morning after<\/a>&#8221; qui s&#8217;inqui\u00e8te de la jurisprudence cr\u00e9\u00e9e par la Commission et le Tribunal Europ\u00e9en. Car, on sait que cela a commenc\u00e9 avec la volont\u00e9 de r\u00e9duire la puissance de Microsoft, mais jusqu&#8217;o\u00f9 cela pourrait-il aller? Car potentiellement: &#8220;<em>It condemns dominant firms that bundle new features into their products if those features could be supplied independently by other firms&#8211;even though bundling is a common way for all firms, dominant or not, to improve their products&#8221;. <\/em>Sachant que l&#8217;article oublie toutefois que les &#8220;prises&#8221; doivent \u00eatre bien visibles et m\u00e9diatiques pour avoir un poids politique!<\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image23.png\" atomicselection=\"true\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"236\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb22.png\" width=\"381\" border=\"0\"><\/a> <\/p>\n<blockquote>\n<p>Enfin, le D\u00e9partement de la Justice Am\u00e9ricain qui <a href=\"http:\/\/useu.usmission.gov\/Dossiers\/Antitrust\/Sep1707_Barnett_Microsoft.asp\">tr\u00e8s officiellement<\/a> voit un danger \u00e0 des mesures qui favorisent plus les concurrents qu&#8217;elles n&#8217;aident les consommateurs. Les am\u00e9ricains trouvent que l&#8217;Europe va trop loin dans ses tentatives de r\u00e9gulation de ce march\u00e9 du logiciel. Et en g\u00e9n\u00e9ral d&#8217;ailleurs. R\u00e9action qui a \u00e9videmment plus qu&#8217;agac\u00e9 la Commission Europ\u00e9enne qui voit l\u00e0 une ing\u00e9rence inacceptable dans des d\u00e9cisions de justice.<\/p>\n<\/blockquote>\n<p>Et au passage, Microsoft n&#8217;a pas indiqu\u00e9 s&#8217;il souhaitait faire appel de la d\u00e9cision. C&#8217;est toujours possible mais le droit europ\u00e9en limite curieusement la capacit\u00e9 \u00e0 faire appel sur le fond du dossier. Microsoft ne peut faire appel que sur la forme juridique de la d\u00e9cision de la Commission. Ce qui laisse peu de marge.<\/p>\n<p><strong>L&#8217;illusion de l&#8217;impact sur le march\u00e9<\/strong><\/p>\n<p>A mon sens, les d\u00e9cisions de la Commission Europ\u00e9enne donnent l&#8217;illusion d&#8217;une r\u00e9gulation du monopole de&nbsp;Microsoft et d&#8217;avoir un impact r\u00e9el sur le march\u00e9. Or il est tr\u00e8s marginal, malgr\u00e9 toutes les sanctions&nbsp;imagin\u00e9es par Bruxelles. C&#8217;est un peu du cin\u00e9ma&nbsp;politique!<\/p>\n<p>Leur pouvoir sur les grands monopoles et de structuration du march\u00e9 est pourtant bien r\u00e9el sur les industries traditionnelles (comme la&nbsp;fusion avort\u00e9e Legrand-Scheider). C&#8217;est d&#8217;ailleurs surtout un pouvoir d&#8217;obstruction. Mais il devient moins op\u00e9rant dans les technologies de l&#8217;information o\u00f9 jouent des \u00e9conomies de r\u00e9seau puissantes et o\u00f9 l&#8217;immat\u00e9riel et l&#8217;Internet chamboulent la donne. Dans ce monde, les forces du march\u00e9 sont plus grandes et plus rapides que ces forces politiques, qui ont trop souvent un voire plusieurs trains de retard.<\/p>\n<p>L&#8217;exemple le plus flagrant est Firefox qui a r\u00e9ussi \u00e0 gagner des parts de march\u00e9 comprises entre 25% et 30% &#8211; en particulier en Europe &#8211; alors que les mesures impos\u00e9es par Bruxelles n&#8217;avaient aucun lien avec IE!&nbsp; Parce que Microsoft s&#8217;\u00e9tait endormi sur ses lauriers avec Internet Explorer, et aussi, un peu ralenti par les soucis concernant la s\u00e9curit\u00e9 de ses logiciels syst\u00e8mes, choses qui ont peu \u00e0 voir avec les proc\u00e9dures antitrust. La baisse de part de march\u00e9 d&#8217;Internet Explorer (en fait, on devrait parler de part d&#8217;usage car les navigateurs sont presque tous gratuits) est la cons\u00e9quence directe de la dominance de Microsoft sur son march\u00e9 et dans un mouvement de balancier assez in\u00e9luctable. Internet Explore 7.0 est bien sorti mais il n&#8217;a pas suffit pour changer la donne et la progression de Firefox. Ce dernier a notamment pour lui une meilleure architecture d&#8217;extensibilit\u00e9 qu&#8217;IE avec&nbsp;des plug-ins qui s&#8217;installent et se mettent \u00e0 jour plus facilement. Ils sont rassembl\u00e9s sur un site de Firefox. Ah, toujours l&#8217;\u00e9cosyst\u00e8me! C&#8217;est pourtant une force de Microsoft mais La fondation Mozilla&nbsp; a r\u00e9ussi \u00e0 doubler Microsoft \u00e0 ce jeu. Ce sont donc les &#8220;forces du march\u00e9&#8221; (surtout, celles de Firefox, coupl\u00e9es aux faiblesses de Microsoft) qui ont ouvert la voie de la concurrence. Pas la r\u00e9gulation! Entre temps, il faut dire que les frayeurs d&#8217;un contr\u00f4le de l&#8217;Internet par Microsoft se sont amenuis\u00e9es!<\/p>\n<p>Au contraire, dans le domaine o\u00f9 la Commission voulait infl\u00e9chir le march\u00e9, rien n&#8217;a chang\u00e9. Windows Media Player et ses formats sont toujours l\u00e0 et dominent le march\u00e9, notamment l\u00e0 o\u00f9 il y a du DRM, et Apple couvre le reste avec ses formats et DRM, l\u00e0 o\u00f9 il y a des iPods, c&#8217;est-\u00e0-dire&#8230; dans presque toutes les poches. Mais la Commission va-t-elle forcer Apple \u00e0 ouvrir son format pour le rendre interop\u00e9rable avec d&#8217;autres syst\u00e8mes que iTunes et l&#8217;iPod? Ce n&#8217;est pas encore \u00e0 l&#8217;ordre du jour et si elle s&#8217;en pr\u00e9occupe, elle prendra une d\u00e9cision dans cinq \u00e0 sept ans. Un bail dans cette industrie! La Commission utilise des raisonnements qui sont compl\u00e8tement d\u00e9pass\u00e9s \u00e0 l&#8217;heure de l&#8217;Internet, du &#8220;software as a service&#8221; et des nouvelles chaines de valeur qui se cr\u00e9ent.<\/p>\n<p>On pourra arguer de ce qu&#8217;Internet Explorer n&#8217;est pas autant li\u00e9 \u00e0 l&#8217;offre serveur Microsoft que ne l&#8217;est Windows Media. Certes, mais les formats sp\u00e9cifiques de Windows Media Player, notamment le VC-1 pour la vid\u00e9o, sont standardis\u00e9s et largement g\u00e9n\u00e9r\u00e9s par des logiciels tiers. Donc, en mettant de c\u00f4t\u00e9 l&#8217;\u00e9pineux sujet du DRM, l&#8217;interop\u00e9rabilit\u00e9 est assur\u00e9e.<\/p>\n<p>Pour ce qui est des serveurs, l&#8217;impact est tout aussi maigre. La part de march\u00e9 de Windows Server est \u00e0 peu pr\u00e8s stable depuis cinq ans. L&#8217;alternative, c&#8217;est Linux et ses logiciels d&#8217;infrastructure compl\u00e9mentaires. Mais pas gr\u00e2ce \u00e0 la commission qui aurait frein\u00e9 Microsoft. Plus simplement, parce que Linux est dominant sur le Web et que les applications sont de plus en plus architectur\u00e9es sur des mod\u00e8les Web. De plus, si Linux perce, c&#8217;est gr\u00e2ce \u00e0 ses qualit\u00e9s propres, et du fait d&#8217;erreurs tactiques de Microsoft, comme le d\u00e9sastreux lancement de ses nouveaux programmes de licencing en 2001. Mais ce n&#8217;est pas li\u00e9 aux proc\u00e9dures&nbsp;antitrust!<\/p>\n<p><strong>L&#8217;int\u00e9gration de fonctionnalit\u00e9s dans Windows<\/strong><\/p>\n<p>L&#8217;approche corrective de la Commission Europ\u00e9enne autour de Windows Media Player est curieusement diam\u00e9tralement oppos\u00e9e \u00e0 celle qu&#8217;ils ont appliqu\u00e9 dans les serveurs. Dans un cas, ils poussent au &#8220;d\u00e9bundling&#8221;. Dans l&#8217;autre, ils poussent \u00e0 l&#8217;interop\u00e9rabilit\u00e9. Pourquoi n&#8217;avoir pas pouss\u00e9 \u00e0 l&#8217;un ou l&#8217;autre, de mani\u00e8re coh\u00e9rente?<\/p>\n<p>On sait bien que la demande de la Commission Europ\u00e9enne de retirer Windows Media Player de Windows dans une version propos\u00e9e aux constructeurs n&#8217;a eu aucun impact. Commercialis\u00e9e au m\u00eame prix que la version compl\u00e8te, cette version r\u00e9duite de Windows n&#8217;a pas trouv\u00e9 son march\u00e9. La Commission impose \u00e0 Microsoft de proposer aux OEMs une version de Windows sans Media Player. Mais&nbsp;le choix des OEMs n&#8217;est pas celui des consommateurs! Et de toutes mani\u00e8res, l&#8217;outil est t\u00e9l\u00e9chargeable sur Windows Update et ailleurs, comme tous les lecteurs multim\u00e9dia de la plan\u00e8te. Et \u00e0 l&#8217;heure o\u00f9 la fronti\u00e8re entre logiciel et services Internet s&#8217;amenuise, la d\u00e9cision de la Commission Europ\u00e9enne perd de sa raison d&#8217;\u00eatre.<\/p>\n<p>L&#8217;autre incoh\u00e9rence de la Commission provient de l&#8217;impr\u00e9dictibilit\u00e9 qu&#8217;elle cr\u00e9\u00e9. Il n&#8217;y a pas vraiment de d\u00e9finition claire de l\u00e0 o\u00f9 cela commence et l\u00e0 o\u00f9 cela s&#8217;arr\u00eate. C&#8217;est \u00e0 Microsoft de les deviner en fonction &#8220;du droit&#8221;.&nbsp; Ce qui commence \u00e0 inqui\u00e9ter l&#8217;industrie informatique (Intel, Apple, Google entre autres).<\/p>\n<p>Il y a au moins cinq cas concernant Windows qui pourraient g\u00e9n\u00e9rer les foudres de la Commission mais ne l&#8217;ont pas encore fait :<\/p>\n<ul>\n<li>La fonction de <strong>d\u00e9fragmentation<\/strong> du disque dans Windows qui concurrence pourtant les outils de d\u00e9fragmentation ind\u00e9pendants.&nbsp;Ce qui sauve indirectement Microsoft, c&#8217;est que cette&nbsp;fonction int\u00e9gr\u00e9e dans Windows est licenci\u00e9e \u00e0 une soci\u00e9t\u00e9 externe, DiskKeeper, et qu&#8217;elle est rudimentaire.&nbsp;Autre raisonnement: il n&#8217;y a pas de liens avec une offre serveur ni d&#8217;\u00e9conomie de r\u00e9seau particuli\u00e8re autour de ce genre d&#8217;outil. Mais si un \u00e9diteur d&#8217;outils de d\u00e9fragmentation attaquait Microsoft? Il aurait peu de chances d&#8217;\u00eatre \u00e9cout\u00e9 car, petite entreprise, il manquerait de moyens. La Commission Europ\u00e9enne \u00e9coute surtout&nbsp;des soci\u00e9t\u00e9s concurrentes de Microsoft de taille respectable: IBM, Sun, Novell, AOL et qui ont les moyens de se payer des avocats et des lobbyistes!<\/li>\n<li>Le <strong>desktop search <\/strong>est aussi int\u00e9ressant. Avec Google <a href=\"http:\/\/www.news.com\/Has-Google-actually-read-U.S.-v.-Microsoft\/2010-1014_3-6208945.html?part=rss&amp;tag=2547-1_3-0-20&amp;subj=news\">qui demande&nbsp;<\/a>et demande la prolongation de la surveillance de Microsoft dans le suivi de l&#8217;accord \u00e0 l&#8217;amiable conclu en 2002 avec le DOJ (Department of Justice, US).&nbsp; Pourtant, le dominant dans ce march\u00e9, c&#8217;est plut\u00f4t Google. Mais Microsoft pourrait &#8220;\u00e9tendre son monopole de Windows \u00e0 celui du search sur le web gr\u00e2ce \u00e0 cette int\u00e9gration&#8221;. Encore faudrait-il prouver que l&#8217;int\u00e9gration du desktop search dans Windows a un impact r\u00e9el sur l&#8217;usage de moteurs de recherche sur Internet et qu&#8217;il correspond \u00e0 un march\u00e9 en soi, alors que la fonction &#8220;search&#8221; a \u00e9t\u00e9 plac\u00e9e dans une foultitude d&#8217;endroits dans l&#8217;interface utilisateur de Vista. En attendant, Microsoft modifie Vista pour permettre l&#8217;usage de moteurs ind\u00e9pendants en lieu et place du sien. Et, comme pour Windows Media Player qui est dans Windows depuis 1992, la fonction de recherche de fichiers est dans Windows depuis au moins aussi longtemps. C&#8217;est juste le mod\u00e8le d&#8217;indexation et son interface qui a \u00e9volu\u00e9 dans le temps. Et Microsoft a r\u00e9pliqu\u00e9 \u00e0 Google en cherchant \u00e0 emp\u00eacher avec d&#8217;autres l&#8217;acquisition par ce dernier de DoubleClick.<\/li>\n<li>Les <strong>antivirus<\/strong>. Si la solidit\u00e9 de Windows \u00e9tait plus grande au point de permettre de se passer d&#8217;antivirus, les \u00e9diteurs d&#8217;antivirus attaqueraient-ils Microsoft? Ici, Microsoft a \u00e9t\u00e9 prudent: ses technologies gratuites ou pas ne sont pas en standard dans Windows Vista mais sont &#8220;juste&#8221; t\u00e9l\u00e9chargeables. Et factur\u00e9es s\u00e9par\u00e9ment (pour l&#8217;antivirus Live One Care, mais pas pour l&#8217;antispyware Defender).<\/li>\n<li>Le <strong>traitement des photos<\/strong>, qui s&#8217;est enrichi avec Windows Photo Gallery dans Windows. Il permet \u00e0 la fois leur agencement et leur correction. Bien entendu, sans atteindre le niveau de fonctionnalit\u00e9s d&#8217;un Photoshop ou de TheGIMP. Cela permet d&#8217;\u00e9viter les foudres de la concurrence et de la Commission Europ\u00e9enne. Mais jusqu&#8217;\u00e0 quand?&nbsp;Surtout avec la prochaine version de Windows Photo Gallery, li\u00e9e aux services Windows Live sur Internet.&nbsp;<\/li>\n<li>L&#8217;int\u00e9gration du nouveau <strong>format XPS<\/strong> dans Windows Vista et Office 2007, sorte de concurrent du PDF d&#8217;Adobe. Cela fait 9 mois que c&#8217;est sur mon PC, &#8220;bundl\u00e9&#8221;. Mais je n&#8217;en ai jamais vu la couleur \u00e0 part quelques cas de figure o\u00f9 le site Web de Microsoft Corp proposait telle ou telle documentation avant-vente uniquement dans ce format et celui de Word 2007. Sinon, j&#8217;utilise et g\u00e9n\u00e8re toujours du PDF. Mais Adobe a menac\u00e9 d&#8217;attaquer Microsoft. Et depuis, on n&#8217;en parle plus. <\/li>\n<\/ul>\n<p>Les r\u00e8gles \u00e0 appliquer pour int\u00e9grer ou pas de fonctionnalit\u00e9s dans Windows sans risquer les foudres de l&#8217;antitrust sont donc implicites : faciliter le remplacement des ces fonctionnalit\u00e9s par des \u00e9quivalents non-Microsoft, ne pas \u00eatre li\u00e9 \u00e0 une \u00e9conomie de r\u00e9seau significative (comme autour des contenus), et ne pas g\u00eaner de gros concurrent.<\/p>\n<p>Microsoft aurait du aller jusqu&#8217;au bout d&#8217;une d\u00e9marche sur l&#8217;interop\u00e9rabilit\u00e9 pour \u00e9viter de se voir g\u00eaner dans l&#8217;int\u00e9gration. En effet, &#8220;l&#8217;innovation par l&#8217;int\u00e9gration&#8221; d\u00e9fendue par l&#8217;\u00e9diteur est un incontournable de cette industrie. Regardez bien autour de vous: les principales nouveaut\u00e9s de l&#8217;Internet, du logiciel et du mat\u00e9riel sont la juxtaposition plus ou moins \u00e9l\u00e9gante de fonctionnalit\u00e9s disparates. Tel syst\u00e8me de blog int\u00e8gre une messagerie, tel r\u00e9seau social s&#8217;attaque aux mobiles, tel t\u00e9l\u00e9phone devient baladeur MP3, etc. Il est donc critique, m\u00eame pour un &#8220;monopole&#8221;, de pr\u00e9server cette capacit\u00e9 d&#8217;innovation car elle est l&#8217;un des moteurs de son industrie. Pour une soci\u00e9t\u00e9 dominante, cela ne peut se faire qu&#8217;au prix d&#8217;une interop\u00e9rabilit\u00e9 et d&#8217;une interchangeabilit\u00e9 des composants. Windows a bien \u00e9volu\u00e9 ces derni\u00e8res ann\u00e9es pour permettre cela. On peut remplacer et configurer les diff\u00e9rents composants de communication (email, etc) dans Windows XP comme dans Vista (<em>exemple de ce dernier ci-dessous<\/em>). <\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image24.png\" atomicselection=\"true\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"346\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb23.png\" width=\"347\" border=\"0\"><\/a> <\/p>\n<p>Ces nouvelles pratiques de Microsoft sont bien une cons\u00e9quence des proc\u00e9dures antitrust. Mais pour autant, elles n&#8217;ont pas r\u00e9ellement modifi\u00e9 la position de Microsoft sur ses march\u00e9s. Elles l&#8217;ont par contre pouss\u00e9 \u00e0 mieux documenter ses logiciels, \u00e0 les rendre plus modulaires et \u00e0 utiliser de plus de plus, si ce n&#8217;est de cr\u00e9er, des protocoles et formats ouverts, souvent bas\u00e9s sur XML et les Web Services XML.<\/p>\n<p>Au passage, la position d&#8217;Office n&#8217;a jamais \u00e9t\u00e9 mise en cause alors que le logiciel b\u00e9n\u00e9ficie d&#8217;une part de march\u00e9 voisine de celle de Windows (&gt;90%) et qu&#8217;il est le r\u00e9sultat d&#8217;une int\u00e9gration croissante de nouvelles fonctionnalit\u00e9s. Est-ce la prochaine bataille en vue? Oui, mais par d&#8217;autres biais, celui de la normalisation des formats de donn\u00e9es avec l&#8217;ODF (d&#8217;OpenOffice) face \u00e0 OpenXML (celui d&#8217;Office), tous deux b\u00e2tis sur XML.<\/p>\n<p><strong>L&#8217;interop\u00e9rabilit\u00e9 client-serveur<\/strong><\/p>\n<p>Le sujet est plus difficile d&#8217;abord que celui de Windows Media Player. En gros, la Commission Europ\u00e9enne a jug\u00e9 que Microsoft \u00e9tait \u00e9galement &#8220;trop&#8221; dominant sur le march\u00e9 des serveurs et que cette dominance \u00e9tait li\u00e9e aux relations techniques entre Windows sur le poste de travail et Windows Server, notamment dans la gestion de domaines.<\/p>\n<p>La Commission&nbsp;a donc demand\u00e9 \u00e0 Microsoft de fournir les \u00e9l\u00e9ments de documentation permettant \u00e0 des concurrents d&#8217;\u00e9muler le fonctionnement de Windows Server. Chose attendue par exemple par les \u00e9quipes du logiciel open source&nbsp;Samba.<\/p>\n<p>Microsoft a fourni de la documentation (des milliers de pages) et les codes sources de Windows Server. Mais cela n&#8217;a pas suffit. La Commission a aussi exig\u00e9 que les licences d&#8217;utilisation soient moins ch\u00e8res que ce que Microsoft proposait. Le conflit court toujours \u00e0 ce sujet. Microsoft voit d&#8217;un mauvais oeil sa R&amp;D sur les serveurs potentiellement &#8220;donn\u00e9e&#8221; aux concurrents.<\/p>\n<p>Le probl\u00e8me pour Microsoft, c&#8217;est que ses logiciels ne sont pas forc\u00e9ment con\u00e7us pour permettre ce genre d&#8217;interop\u00e9rabilit\u00e9. Il y a <a href=\"https:\/\/www.oezratty.net\/wordpress\/2006\/condamne-pour-mauvais-genie-logiciel\/\">carence d&#8217;ing\u00e9niering<\/a> autant que de volont\u00e9. Et \u00e9muler parfaitement un logiciel serveur reviendrait \u00e0 devoir imiter tout son fonctionnement, et quasiment de copier ses codes sources.<\/p>\n<p>Mais supposons que Windows Server soit interchangeable avec Linux et d&#8217;autres piles open source dans ses relations avec Windows. Quid d&#8217;Exchange, de SQL Server, de Sharepoint et de la bonne vingtaine de logiciels serveurs de Microsoft? Les clients choisissent souvent Windows Server pour profiter du reste de l&#8217;offre serveur de l&#8217;\u00e9diteur. L&#8217;int\u00e9gration et l&#8217;interd\u00e9pendance entre ces diff\u00e9rents composants est une facteur diff\u00e9rentiant cl\u00e9. Est-ce que la Commission va s&#8217;y attaquer et exiger d&#8217;autres documentations, relatives \u00e0 ces logiciels, ou exiger qu&#8217;ils puissent fonctionner sur des syst\u00e8mes concurrents et compatibles avec Windows Server? C&#8217;est un peu la boite de Pandore.<\/p>\n<p><strong>Autres cons\u00e9quences des proc\u00e9dures antitrust<\/strong><\/p>\n<p>Les mesures antitrust vis \u00e0 vis de Microsoft de la Commission Europ\u00e9enne et dans une mesure voisine, de celles du D\u00e9partement de la Justice Am\u00e9ricain ont tout de m\u00eame eu un impact sur l&#8217;\u00e9diteur. Pas vraiment sur ses parts de march\u00e9, mais certainement un peu sur ses pratiques, notamment d&#8217;ing\u00e9niering logiciel, mais surtout dans d&#8217;autres dimensions que voici :<\/p>\n<ul>\n<li>Sur le <strong>porte-monnaie <\/strong>de Microsoft et de ses actionnaires<\/li>\n<\/ul>\n<p>L&#8217;impact est significatif. Au total depuis 2000, les proc\u00e9dures antitrust contre Microsoft lui ont co\u00fbt\u00e9 plus de $8,3B. Plus que le profit g\u00e9n\u00e9r\u00e9 par Microsoft pendant ses 22 premi\u00e8res ann\u00e9es d&#8221;existence (jusqu&#8217;en 1997)! Et le double de son r\u00e9sultat net de 1998, ann\u00e9e du d\u00e9marrage des proc\u00e9dures antitrust am\u00e9ricaines et europ\u00e9enne.<\/p>\n<p>La seule puissance publique qui en ait b\u00e9n\u00e9fici\u00e9 est la Commission Europ\u00e9enne, \u00e0 hauteur d&#8217;environ&nbsp;$900m. Microsoft finance ainsi malgr\u00e9 lui &#8211; et modestement &#8211; la Politique Agricole Commune (premier budget de l&#8217;Union Europ\u00e9enne) ou bien les projets FP6\/FP7 (subventions \u00e0 des projets de recherche dans les TICs). Suivent les grands et petits concurrents de Microsoft (IBM, Sun, AOL, Real Networks, Be Inc) qui ont b\u00e9n\u00e9fici\u00e9 d&#8217;accords \u00e0 l&#8217;amiable avec esp\u00e8ces sonnantes et tr\u00e9buchantes. Suivent en dernier des consommateurs et associations de certaines \u00e9tats des USA qui avaient d\u00e9clench\u00e9 des Class Action (sur un sujet assez fallacieux concernant le prix de la mise \u00e0 jour de Windows 98).<\/p>\n<p>Ces co\u00fbts ont affect\u00e9 significativement la marge nette de l&#8217;\u00e9diteur, jusqu&#8217;\u00e0 presque 7% du revenu en 2004 (<em>sources: quarterly reports de Microsoft compil\u00e9s par l&#8217;auteur<\/em>): <\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image25.png\" atomicselection=\"true\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"224\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb24.png\" width=\"374\" border=\"0\"><\/a><\/p>\n<p>Cela n&#8217;a pas emp\u00each\u00e9 Microsoft de pr\u00e9server de confortables marges nettes, stabilis\u00e9es maintenant autour de 27% du chiffre d&#8217;affaire.&nbsp;C&#8217;est l&#8217;effet du volume des ventes de leurs logiciels. Et encore, cette marge serait bien plus \u00e9lev\u00e9e si Microsoft ne perdait pas autant d&#8217;argent avec MSN et la XBOX!<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image26.png\" atomicselection=\"true\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; border-left: 0px; border-bottom: 0px\" height=\"225\" alt=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/image-thumb25.png\" width=\"376\" border=\"0\"><\/a> <\/p>\n<p>La facture de l&#8217;antitrust pour Microsoft a donc surtout \u00e0 renflouer les caisses de certains &#8220;concurrents&#8221; mal en point et tous am\u00e9ricains! Comme Novell qui doit ses d\u00e9boires plus \u00e0 ses erreurs strat\u00e9giques internes qu&#8217;\u00e0 Microsoft. Que dire en effet de ce &#8220;loser&#8221; parfait de l&#8217;Internet qui n&#8217;a int\u00e9gr\u00e9 nativement le protocole du r\u00e9seau des r\u00e9seaux (TCP\/IP) dans Netware qu&#8217;en 1999, quatre ans apr\u00e8s l&#8217;explosion du Web? Idem pour AOL, engonc\u00e9 \u00e0 la fin des ann\u00e9es 1990 dans une approche de portail ferm\u00e9! Et Sun, le cr\u00e9ateur de Java, qui n&#8217;en a jamais vraiment retir\u00e9 une source de croissance significative, et n&#8217;a senti venir le vent de Linux \u00e0 temps pour adapter son offre serveur.<\/p>\n<ul>\n<li>Sur les <strong>investissements de Microsoft <\/strong>dans son \u00e9cosyst\u00e8me<\/li>\n<\/ul>\n<p>Les aides aux startups, les programmes de recherche avec les laboratoires Europ\u00e9ens, les aides diverses aux \u00e9conomies locales sont la combinaison d&#8217;approches dites citoyennes et d&#8217;int\u00e9gration avec le tissus \u00e9conomique local. Les proc\u00e9dures antitrust ont g\u00e9n\u00e9r\u00e9 indirectement ce ph\u00e9nom\u00e8ne sur la base du raisonnement suivant: l&#8217;\u00e9diteur est injustement attaqu\u00e9 et c&#8217;est \u00e0 cause d&#8217;une image n\u00e9gative. Il faut donc investir localement pour am\u00e9liorer l&#8217;image. Et cela a plut\u00f4t bien fonctionn\u00e9. M\u00eame en Chine.<\/p>\n<p>Microsoft entretenait l&#8217;illusion que tout cela allait les aider dans le cadre de la proc\u00e9dure antitrust europ\u00e9enne, en se faisant de nouveaux amis qui manquaient tant. Mais cela n&#8217;a pas eu cet effet escompt\u00e9 sur la Commission Europ\u00e9enne et sa division de la concurrence. Cela a am\u00e9lior\u00e9 cependant leur image et marginalis\u00e9 l&#8217;impact de ces affaires antitrust, finalement plus pilot\u00e9es par l&#8217;int\u00e9r\u00eat des concurrents que par celui des consommateurs.<\/p>\n<p>Ces actions ont m\u00eame plut\u00f4t renforc\u00e9 la position de Microsoft dans ces r\u00e9gions! Leur int\u00e9gration avec le tissu local d&#8217;innovation s&#8217;est am\u00e9lior\u00e9. Leur \u00e9cosyst\u00e8me s&#8217;est renforc\u00e9. <\/p>\n<p>Le cas des startups est \u00e9loquent. Dans les ann\u00e9es 1990, les startups avaient peur de Microsoft. La rumeur voulait que Microsoft rachetait tous ses concurrents. C&#8217;\u00e9tait d&#8217;abord faux. A part quelques rares exceptions comme Fox Software (concurrent d&#8217;Access mais aussi de dBase et Paradox), Microsoft a toujours fait l&#8217;acquisition de soci\u00e9t\u00e9s compl\u00e9tant son portefeuille et enrichissant ses propres produits. On peut toujours penser que tel ou tel composant int\u00e9gr\u00e9 \u00e0 post\u00e9riori dans Windows ou Office \u00e9tait concurrent de ces logiciels. Mais c&#8217;est vraiment pr\u00e9somptueux. Et que l&#8217;on sache, Microsoft n&#8217;a pas rachet\u00e9 Java, Linux, Notes, Netware, Wordperfect, 1-2-3 ni RealNetworks ni Apple. Et les temps ont chang\u00e9. L&#8217;image de Microsoft qui \u00e9tait d\u00e9sastreuse dans la Silicon Valley s&#8217;est am\u00e9lior\u00e9e apr\u00e8s son installation d&#8217;un campus de plus de 1000 collaborateurs \u00e0 Mountain View, pas loin de Sun (<em>ci-contre, le long de la l\u00e9gendaire 101<\/em>). Et apr\u00e8s avoir appris \u00e0 c\u00f4toyer les acteurs du capital risque et lanc\u00e9 le programme IDEES en France, l&#8217;id\u00e9e a fait son chemin en France au point de devenir un exemple \u00e0 imiter pour les autres, y compris, c&#8217;est un comble, par de grands groupes industriels fran\u00e7ais.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/microsoft-mountain-view-campus.jpg\" atomicselection=\"true\"><img loading=\"lazy\" decoding=\"async\" style=\"border-right: 0px; border-top: 0px; margin: 15px 0px 15px 20px; border-left: 0px; border-bottom: 0px\" height=\"338\" alt=\"Microsoft Mountain View campus\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/microsoft-mountain-view-campus-thumb.jpg\" width=\"290\" align=\"right\" border=\"0\"><\/a> <\/p>\n<p>De plus, l&#8217; &#8220;exit strategy&#8221; r\u00eav\u00e9e de nombreux fondateurs de startups, c&#8217;est d&#8217;\u00eatre rachet\u00e9 par Google ou Microsoft. A ceci pr\u00e8s qu&#8217;elle pr\u00e9sente l&#8217;inconv\u00e9nient pour Microsoft de devoir dans la plupart des cas plier bagage pour la r\u00e9gion de Seattle. Et aussi, de voir ces acquisitions intervenir trop t\u00f4t dans le cycle de croissance de la soci\u00e9t\u00e9, et donc de g\u00e9n\u00e9rer une transaction mod\u00e9r\u00e9e (de l&#8217;ordre de 1 \u00e0 2 millions de $ par d\u00e9veloppeurs&#8230; ce qui est tout de m\u00eame pas mal et paye largement les frais de d\u00e9m\u00e9nagement).<\/p>\n<p>En se rapprochant des startups, comme en France, Microsoft fait moins peur et devient au minimum une boite presque normale, et au mieux, une boite exemplaire, qui aide les startups de son \u00e9cosyst\u00e8me. Tout en le renfor\u00e7ant. Tout en permettant quelques acquisitions. Rien qu&#8217;en France, deux startups ont \u00e9t\u00e9 ainsi absorb\u00e9es entre 2006 et 2007 (MotionBridge et ScreenTonic) alors qu&#8217;aucune ne l&#8217;avait \u00e9t\u00e9 auparavant!<\/p>\n<p>Comme en parall\u00e8le, Microsoft grandit et s&#8217;alourdit, le risque de le voir concurrencer les startups sur des produits plus niches s&#8217;amenuise. Les capacit\u00e9s marketing de Microsoft sont souvent bien sur\u00e9valu\u00e9es dans les produits autres que les quatre o\u00f9 cinq o\u00f9 ils ont plus de 50% de parts de march\u00e9. Et en particulier dans les solutions verticales ou sp\u00e9cialis\u00e9es o\u00f9 ils sont soit non pr\u00e9sents, soient pr\u00e9sents avec des forces terrain tr\u00e8s faibles quantitativement. La force de la marque aide, mais c&#8217;est loin d&#8217;\u00eatre l&#8217;arme fatale face \u00e0 de petits acteurs sp\u00e9cialis\u00e9s et bien focalis\u00e9s!<\/p>\n<p>Net net, Microsoft s&#8217;est renforc\u00e9 avec son \u00e9cosyst\u00e8me qui ne le craint plus comme avant. Et il peut b\u00e9n\u00e9ficier plus facilement d&#8217;innovations externes alors que l&#8217;interne risque de s&#8217;ass\u00e9cher.<\/p>\n<ul>\n<li>Sur la <strong>posture g\u00e9n\u00e9rale de Microsoft <\/strong><\/li>\n<\/ul>\n<p>Les proc\u00e9dures antitrust ont eu les effets d&#8217;une guerre psychologique vis \u00e0 vis de Microsoft. Les proc\u00e9dures antitrust et les probl\u00e8mes d&#8217;image associ\u00e9s, ont pu un temps ralentir la capacit\u00e9 \u00e0 recruter des talents, mais il semble que cela ne soit plus le cas depuis longtemps. Cela fatiguait aussi les collaborateurs, us\u00e9s de se voir critiqu\u00e9s \u00e0 tout bout de champs dans leur vie priv\u00e9e (mais dans la majeure partie des cas, pour&#8230; du support technique).<\/p>\n<p>Microsoft craignait surtout d&#8217;\u00eatre victime de l&#8217;immobilisation qui a marqu\u00e9 IBM \u00e0 partir de 1982, apr\u00e8s la conclusion d&#8217;un accord \u00e0 l&#8217;amiable avec le D\u00e9partement de la Justice am\u00e9ricain faisant suite \u00e0 14 ann\u00e9es de proc\u00e9dures antitrust. L&#8217;IBMisation comme on l&#8217;appelle si bien est toujours \u00e0 l&#8217;affut. C&#8217;est la combinaison d&#8217;une culture de grande boite et ses pesanteurs hi\u00e9rarchiques, avec les craintes juridiques associ\u00e9es \u00e0 toute nouvelle initiative. Chez Microsoft, elle est plus le r\u00e9sultat de l&#8217;effet de taille et d&#8217;autres aspects comme le ralentissement de la croissance. L&#8217;IBMisation lancinante fera plus de mal que toute proc\u00e9dure antitrust sur la capacit\u00e9 d&#8217;innovation de la soci\u00e9t\u00e9.<\/p>\n<p>La posture de Microsoft a aussi chang\u00e9 dans ses relations clients. La soci\u00e9t\u00e9 a compris la relation qui existait entre certains probl\u00e8mes d&#8217;image n\u00e9gative et ceux qui sont relatifs \u00e0 la satisfaction client. Des efforts ont \u00e9t\u00e9 entrepris pour am\u00e9liorer les deux en parall\u00e8le et ils payent progressivement, m\u00eame si ceux-ci ont tendance \u00e0 \u00eatre plus tourn\u00e9s vers les entreprises que vers le grand public. Certains efforts \u00e0 destination des grandes entreprises, des PME, des d\u00e9veloppeurs, des \u00e9tudiants, des informaticiens en g\u00e9n\u00e9ral, rel\u00e8vent \u00e0 la fois d&#8217;un optique orient\u00e9e &#8220;satisfaction client&#8221; et d&#8217;une optique business classique. Ils ont encore du chemin \u00e0 parcourir, mais la prise de conscience est l\u00e0.<\/p>\n<ul>\n<li>Sur les relations avec <strong>ses concurrents<\/strong><\/li>\n<\/ul>\n<p>Comme l&#8217;origine de nombreuses proc\u00e9dures antitrust provenaient de grands concurrents et que, par ailleurs, l&#8217;exigence de l&#8217;interop\u00e9rabilit\u00e9 est incontournable chez les grands clients, Microsoft a fait l&#8217;effort de se rapprocher de ses concurrents sur ce th\u00e8me. <\/p>\n<p>Il en a r\u00e9sult\u00e9 d&#8217;\u00e9tonnants accords de partenariat avec Novell et Sun, parmi d&#8217;autres. Microsoft a aussi promu les Web Services avec IBM au d\u00e9but des ann\u00e9es 2000. Microsoft a ainsi cherch\u00e9 \u00e0 pacifier ses relations avec le peu de soci\u00e9t\u00e9s avec qui ils n&#8217;avaient pas naturellement de relations \u00e0 un titre ou \u00e0 un autre. Ils ont m\u00eame cr\u00e9\u00e9 aux USA une petite \u00e9quipe en charge de &#8220;Technology Diplomacy&#8221; juste pour s&#8217;occuper de concurrents existants ou potentiels et nouer des partenariats.<\/p>\n<ul>\n<li>Sur le <strong>lobbying<\/strong><\/li>\n<\/ul>\n<p>Jusqu&#8217;aux affaires antitrust, Microsoft n&#8217;avait pas d&#8217;activit\u00e9 de lobbying. Ils n&#8217;avaient qu&#8217;une personne \u00e0 Washington DC lorsque le proc\u00e8s antitrust a d\u00e9marr\u00e9 aux USA. Depuis, ils se sont rattrap\u00e9s. Ils ont investi en avocats et lobbyistes divers. Ils ont notamment bien enrichi le cabinet d&#8217;avocats <a href=\"http:\/\/www.sullcrom.com\/Home.aspx\">Sullivan &amp; Cromwell<\/a>, dont le si\u00e8ge est bas\u00e9 \u00e0 New York mais qui semble adopter un comportement de texans. On trouve la r\u00e9f\u00e9rence Microsoft&nbsp;<a href=\"http:\/\/www.sullcrom.com\/achievements\/practice\/litigation\/\">ici<\/a> et <a href=\"http:\/\/www.sullcrom.com\/practice\/servicedetail.aspx?firmService=29&amp;pdText=PDInfoText1&amp;pdname=LR020002\">l\u00e0<\/a>&nbsp;sur leur site web. Le cabinet comprend 600 avocats et r\u00e9alise dans les $900m de chiffre d&#8217;affaire, dont probablement plusieurs grosses dizaines avec Microsoft Corp. <\/p>\n<p>Au d\u00e9part, l&#8217;approche de lobbying \u00e9tait d\u00e9fensive. De 1998 \u00e0 2002, il s&#8217;agissait tout bonnement d&#8217;\u00e9viter un d\u00e9mant\u00e8lement! Puis l&#8217;approche est devenue offensive, \u00e0 savoir qu&#8217;elle a touch\u00e9 l&#8217;implication de Microsoft dans diff\u00e9rents sujets de soci\u00e9t\u00e9 incontournables pour un acteur de cette taille: la vie priv\u00e9e, la propri\u00e9t\u00e9 intellectuelle, l&#8217;\u00e9conomie du logiciel, les nouveaux m\u00e9dias num\u00e9riques, la protection de l&#8217;enfance sur Internet, etc. Microsoft a compris qu&#8217;il n&#8217;\u00e9tait pas qu&#8217;un simple \u00e9diteur de logiciel et qu&#8217;il avait une responsabilit\u00e9 face \u00e0 la soci\u00e9t\u00e9. Il s&#8217;est donc impliqu\u00e9 dans les d\u00e9bats associ\u00e9s. Souvent, de mani\u00e8re publique (on appelle cela de la comm ou du marketing), parfois de mani\u00e8re plus discr\u00e8te (on appelle cela du lobbying). <\/p>\n<p>Les d\u00e9tracteurs de Microsoft regretteront que la soci\u00e9t\u00e9 ait acquis ce savoir faire. Mais l\u00e0 encore, l&#8217;antitrust a ouvert une boite de Pandore insoup\u00e7onn\u00e9e. Sans oublier qu&#8217;au d\u00e9part, les proc\u00e9dures \u00e9taient le r\u00e9sultat du lobbying des grands concurrents de Microsoft, bien plus avanc\u00e9s \u00e0 l&#8217;\u00e9poque que ce dernier dans ce sport national am\u00e9ricain!<\/p>\n<p><strong>Ce qui ralentit Microsoft<\/strong><\/p>\n<p>Les proc\u00e9dures antitrust ne ralentissent pas vraiment Microsoft. <\/p>\n<p>Si et quand ralentissement il y a, il est li\u00e9 \u00e0 des causes internes plus classiques, pour l&#8217;essentiel li\u00e9s \u00e0 des effets de seuil provoqu\u00e9s par la taille de l&#8217;entreprise:<\/p>\n<ul>\n<li>L&#8217;<strong>inertie<\/strong> li\u00e9e \u00e0 la taille gargantuesque de l&#8217;\u00e9diteur, qui occupe maintenant plus de 80000 personnes et fait plus de la moiti\u00e9 du chiffre d&#8217;affaire d&#8217;IBM.<\/li>\n<li>La richesse qui les pousse \u00e0 <strong>investir \u00e0 fonds perdus <\/strong>sans se poser forc\u00e9ment les bonnes questions. Ainsi, ils perdent beaucoup de temps. Mais ils ont effectivement le temps pour eux. C&#8217;est le cas pour la XBOX, pour MSN, pour Live mais aussi pour leur initiative MSTV.<\/li>\n<li>La <strong>complexit\u00e9 <\/strong>des logiciels comme Windows qui rend difficile leur \u00e9volution. Le poids de la base install\u00e9e est \u00e0 la fois un atout (qui freine l&#8217;irruption de concurrents) et un fardeau (sa prise en compte complexifie les d\u00e9veloppements, co\u00fbte cher et peut freiner le processus d&#8217;innovation).<\/li>\n<li>Une <strong>organisation <\/strong>pas assez mondiale et distribu\u00e9e du d\u00e9veloppement, encore tr\u00e8s concentr\u00e9e sur la c\u00f4te ouest des USA. M\u00eame si des laboratoires de R&amp;D ont pu \u00eatre r\u00e9cemment ouverts en Chine, et surtout en Inde. Google a une strat\u00e9gie meilleure de ce point de vue l\u00e0 en recrutant et employant les d\u00e9veloppeurs l\u00e0 o\u00f9 ils sont. Ils ont ainsi un lab \u00e0 New York, un \u00e0 Londres et un \u00e0 Zurich. Microsoft n&#8217;a aucun d\u00e9veloppeur sur la c\u00f4te est des USA! Et attirer de bons d\u00e9veloppeurs \u00e0 Seattle n&#8217;est pas si simple que cela.<\/li>\n<li>Une difficult\u00e9 \u00e0 <strong>motiver et recruter de bons collaborateurs <\/strong>qui n&#8217;ont plus de &#8220;stock options&#8221; depuis 2003 mais des programmes d&#8217;attribution d&#8217;actions qui sont bien moins motivants. Un petit tour dans le blog <a href=\"http:\/\/minimsft.blogspot.com\/\">Mini-Microsoft<\/a> permet de sentir ce malaise.<\/li>\n<li>Des difficult\u00e9s \u00e0 <strong>marketer les innovations<\/strong>. Soit le logiciel est dominant et chaque nouveaut\u00e9 est noy\u00e9e dans une masse de plusieurs centaines de changements dure \u00e0 valoriser (citez &#8220;une&#8221; nouveaut\u00e9 critique de Vista&#8230;), soit le logiciel est nouveau et les \u00e9quipes terrain pour le relayer (dans les entreprises) seront peu nombreuses et seront marginalis\u00e9es. Et contrairement \u00e0 ce qui se dit, le marketing de Microsoft est tr\u00e8s in\u00e9gal selon les produits et les activit\u00e9s.<\/li>\n<li>Le grand nombre de <strong>pr\u00e9occupations <\/strong>des clients, surtout en entreprise, et leur dispersion naturelle.<\/li>\n<\/ul>\n<p>Sans compter toutes les erreurs qu&#8217;une organisation de cette taille l\u00e0 peut g\u00e9n\u00e9rer, laissant ainsi un espace libre \u00e0 de nombreux concurrents plus rapides et opportunistes. C&#8217;est particuli\u00e8rement vrai dans le cadre de l&#8217;Internet et du social networking.<\/p>\n<p><strong>Les autres propositions pour freiner Microsoft<\/strong><\/p>\n<p>Le probl\u00e8me pour les d\u00e9tracteurs de Microsoft et les assoiff\u00e9s d&#8217;une plus grande concurrence dans les cat\u00e9gories o\u00f9 l&#8217;\u00e9diteur domine le march\u00e9, ces lourdeurs ne sont pas suffisantes pour le d\u00e9lester de parts de march\u00e9 avec Windows, Windows Server&nbsp;ou Office.<\/p>\n<p>Nelly Kroes, la commissaire europ\u00e9enne en charge de la concurrence, ne se satisferait m\u00eame pas que Microsoft respecte \u00e0 la lettre ses condamnations. Elle voudrait que cela g\u00e9n\u00e8re &#8220;<em>une baisse substantielle de la part de march\u00e9 de Microsoft<\/em>&#8220;! Sans indiquer de chiffre pour autant, mais on sait qu&#8217;au dessus de 50%, on est d\u00e9j\u00e0 consid\u00e9r\u00e9 comme un acteur dominant par Bruxelles. Elle &#8211; et ses pr\u00e9d\u00e9cesseurs &#8211;&nbsp;ont du prendre le probl\u00e8me par tous les bouts et n&#8217;ont visiblement pas trouv\u00e9 grand chose \u00e0 se mettre sous la dent. En effet, il n&#8217;y a pas des masses de solution:<\/p>\n<ul>\n<li>Certains ont propos\u00e9 <strong>d&#8217;interdire l&#8217;int\u00e9gration de Windows dans les PCs<\/strong><\/li>\n<\/ul>\n<p>Le paradoxe est le suivant : cela limiterait l&#8217;acc\u00e8s au march\u00e9 des composants bundl\u00e9s par les constructeurs dans Windows comme le lecteur PDF d&#8217;Adobe! Cela rendrait difficile tout le travail de personnalisation des configurations logicielles r\u00e9alis\u00e9 par les constructeurs. <\/p>\n<p>De deux choses l&#8217;une, o\u00f9 bien les revendeurs proposeraient un DVD avec un Windows g\u00e9n\u00e9rique et il faudrait le configurer \u00e0 la main, ou bien les constructeurs proposeraient leur propre version, comme celle que l&#8217;on retrouve dans le DVD de r\u00e9paration du syst\u00e8me, qu&#8217;il faut souvent graver soi-m\u00eame au moment du premier d\u00e9marrage du PC. Le DVD n&#8217;est pas fourni en standard par les constructeurs pour r\u00e9duire le co\u00fbt et les marges d\u00e9j\u00e0 bien compress\u00e9s des configurations. Et les PC expos\u00e9s dans la distribution seraient bien tristes, avec un \u00e9cran tout noir!<\/p>\n<p>Cela niv\u00e8lerait les PC les uns par rapport aux autres et r\u00e9duirait la capacit\u00e9 des constructeurs \u00e0 se diff\u00e9rentier par le logiciel. Et au passage, cela augmenterait le co\u00fbt unitaire de Windows car vendu \u00e0 l&#8221;unit\u00e9 et pas en volume. Et cela complexifierait le travail pour la distribution qui aurait plus \u00e0 faire, en ajoutant le co\u00fbt&nbsp; du service d&#8217;installation, n\u00e9cessaire pour de nombreux n\u00e9ophytes, qui reviendrait aussi cher que le co\u00fbt de Windows qui est dans le PC!&nbsp; En effet, une heure de technicien vaut plus de 75\u20ac! Et c&#8217;est le temps qu&#8217;il faut pour installer convenablement son syst\u00e8me d&#8217;exploitation, avec, certes, des temps morts. Et puis, cela ne changerait pas la donne dans les entreprises car de toutes mani\u00e8res, ces derni\u00e8res &#8220;masterisent&#8221; leurs PC une fois pour toutes et les installent automatiquement.<\/p>\n<p>Les associations du libre estiment que la part de march\u00e9 de Linux monterait \u00e0 30% si Windows \u00e9tait &#8220;d\u00e9bundl\u00e9&#8221; des PC. Rien n&#8217;est moins sur! Linux a encore quelques progr\u00e8s \u00e0 faire pour pouvoir atteindre cette masse critique d&#8217;utilisateurs. Sinon, cela ferait longtemps qu&#8217;il aurait r\u00e9ussi \u00e0 le faire! <\/p>\n<p>L&#8217;unbundling diminuerait marginalement la part de march\u00e9 de Windows, mais cela serait au d\u00e9triment du confort et du porte-monnaie d&#8217;une majorit\u00e9 des utilisateurs. Faut-il v\u00e9ritablement p\u00e9naliser les clients qui suivent le produit dominant pour aider les autres? Grande question d&#8217;\u00e9quilibre entre libert\u00e9 de choix, d\u00e9mocratie, et facilit\u00e9 d&#8217;achat et d&#8217;installation dans un monde o\u00f9 les utilisateurs ne sont pas experts et souhaitent juste acheter un PC qui fonctionne avec les principaux logiciels et mat\u00e9riels du march\u00e9!<\/p>\n<p>Mais bon, la puissance publique Europ\u00e9enne est tr\u00e8s capable d&#8217;inventer une usine \u00e0 gaz.<\/p>\n<ul>\n<li>D&#8217;autres bataillent autour des <strong>normes et standards<\/strong><\/li>\n<\/ul>\n<p>Le processus de standardisation d&#8217;ODF, puis celui d&#8217;OpenXML, en fait partie. Avec en id\u00e9e sous-jacente chez certains, la perspective de mettre hors jeu Microsoft de march\u00e9s publics. Mais c&#8217;est bien illusoire encore une fois car dos au mur, Microsoft pourra tr\u00e8s bien supporter les formats ODF dans sa suite Office (il le fait via des filtres d\u00e9velopp\u00e9s par des tiers). Mais \u00e9videmment, pas jusqu&#8217;\u00e0 en faire son format natif, bien entendu.<\/p>\n<ul>\n<li>Enfin, les adeptes du logiciel libre appr\u00e9cieraient un encouragement encore plus fort en faveur des logiciels libres et de&nbsp;<strong>Linux<\/strong><\/li>\n<\/ul>\n<p>Les encourager au niveau de l&#8217;enseignement sup\u00e9rieur et de la recherche? C&#8217;est d\u00e9j\u00e0 le cas depuis longtemps, et sans impact sur le poids de Microsoft. En effet, les jeunes informaticiens qui arrivent sur le march\u00e9 du travail s&#8217;adaptent \u00e0 la donne. L\u00e0 dessus comme sur plein d&#8217;autres sujets d&#8217;ailleurs, o\u00f9 l&#8217;enseignement peut \u00eatre d\u00e9cal\u00e9 des r\u00e9alit\u00e9s des entreprises.<\/p>\n<p>Les pousser dans le secteur public? C&#8217;est aussi d\u00e9j\u00e0 largement en place, surtout sur les serveurs. Et l&#8217;on voit des tentatives de placer Linux sur des postes de travail. Avec pour l&#8217;instant, pas assez de recul pour en connaitre l&#8217;impact. Les grands projets (Mairie de Paris, Mairie de Munich) qui avaient fait couler beaucoup d&#8217;encre il y a quelques ann\u00e9es ont l&#8217;air d&#8217;en \u00eatre au point mort pour ce qui est du remplacement de Windows par Linux sur les postes de travail.<\/p>\n<p>Promouvoir l&#8217;open source et cr\u00e9er un&nbsp;Linux Europ\u00e9en? Cela aurait autant de chances d&#8217;aboutir que Quaero. Et que dire de Galileo qui prend des ann\u00e9es de retard pour concurrencer le GPS am\u00e9ricain!<\/p>\n<p>Malgr\u00e9 tout, Linux fera des progr\u00e8s, notamment sur le poste de travail. Parce qu&#8217;il progresse bien et que des distributions comme Ubuntu se pr\u00e9occupent vraiment des utilisateurs lambda.<\/p>\n<p><strong>Que faire?<\/strong><\/p>\n<p>Alors, faut-il juste attendre que Microsoft accumule les erreurs et que les concurrents s&#8217;unissent et renforcent leurs offres? Faut-il attendre que le &#8220;march\u00e9&#8221; fonctionne tout seul et se contenter de batailles d&#8217;escarmouches? Pour les dirigistes et les tenants d&#8217;une forte r\u00e9gulation du lib\u00e9ralisme et de la mondialisation, c&#8217;est s\u00fbrement dur \u00e0 accepter. Mais c&#8217;est un peu la loi de cette industrie, encore bien jeune.<\/p>\n<p>L&#8217;Europe aurait cependant tout \u00e0 gagner \u00e0 r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re de cr\u00e9er des Microsoft locaux, dans la veine des Nokia,&nbsp;SAP, Dassault Syst\u00e8mes et Business Objects, plut\u00f4t que de s&#8217;acharner \u00e0 essayer de d\u00e9plumer Microsoft avec une pince \u00e0 \u00e9piler.<\/p>\n<p>Mais je suis s\u00fbr que vous, amis lecteurs, serez prolixes en id\u00e9es pour revoir la conception de la pince \u00e0 \u00e9piler&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Arr\u00eat du Tribunal de Premi\u00e8re Instance de la Cour Europ\u00e9enne de Justice rendu il y a deux semaines \u00e9tant un peu derri\u00e8re nous, penchons nous avec un peu de recul sur l&#8217;impact de ce document de&nbsp;244 pages bien denses qui reprennent les arguments des deux parties et tranchent en faveur de la Commission sauf sur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,3,18,10],"tags":[],"class_list":["post-421","post","type-post","status-publish","format-standard","hentry","category-economie","category-microsoft","category-politique","category-startups"],"views":15580,"_links":{"self":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/comments?post=421"}],"version-history":[{"count":0,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts\/421\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/media?parent=421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/categories?post=421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/tags?post=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}