{"id":16941,"date":"2018-12-08T16:01:49","date_gmt":"2018-12-08T15:01:49","guid":{"rendered":"https:\/\/www.oezratty.net\/wordpress\/?p=16941"},"modified":"2018-12-20T12:52:08","modified_gmt":"2018-12-20T11:52:08","slug":"le-pari-haut-de-gamme-de-free","status":"publish","type":"post","link":"https:\/\/www.oezratty.net\/wordpress\/2018\/le-pari-haut-de-gamme-de-free\/","title":{"rendered":"Le pari haut de gamme de Free"},"content":{"rendered":"<p>Apr\u00e8s une longue attente, Free lan\u00e7ait enfin sa nouvelle g\u00e9n\u00e9ration de Freebox, les Delta et One, le 4 d\u00e9cembre 2018 (<a href=\"https:\/\/www.youtube.com\/watch?v=45Pldhy_q_E\">vid\u00e9o du lancement<\/a>). La derni\u00e8re annonce datait de 2015 avec la Freebox Mini 4K. Du c\u00f4t\u00e9 des box haut de gamme, il fallait remonter \u00e0 d\u00e9cembre 2010 pour l\u2019annonce de la Freebox R\u00e9volution \u00ab V6 \u00bb. J\u2019avais \u00e0 l\u2019\u00e9poque publi\u00e9 une s\u00e9rie de <a href=\"https:\/\/www.oezratty.net\/wordpress\/2010\/les-entrailles-de-la-freebox-6\/\">quatre articles<\/a> d\u00e9cortiquant le lancement et ses dessous. Faute de temps, je n\u2019ai pas pu r\u00e9\u00e9diter l\u2019exploit et d\u2019autres le font d\u2019ailleurs tr\u00e8s bien comme chez <a href=\"https:\/\/www.nextinpact.com\/news\/107383-les-defis-free-pour-sadapter-au-monde-qui-vient.htm\">NextInpact<\/a><strong>,<\/strong> <a href=\"https:\/\/www.freenews.fr\/freenews-edition-nationale-299\/freebox-9\/dossier-freebox-delta-et-freebox-one-tous-nos-articles-sur-le-lancement\">Freenautes<\/a>, <a href=\"https:\/\/www.frandroid.com\/telecom\/554341_prise-en-main-de-la-freebox-delta?utm_content=buffer2c639&amp;utm_medium=social&amp;utm_source=facebook.com&amp;utm_campaign=buffer\">FrAndroid<\/a> ainsi que <strong>Satellifax<\/strong> et son excellent <a href=\"https:\/\/www.satellifax.com\/fr\/file\/freefile\/54acd3fabd7dab7781a49f12f61cc61c\/satellifax-magazine-40-free-presente-freebox-delta-one.html\">reportage photo du lancement<\/a>.<\/p>\n<p>Je ne peux cependant pas m\u2019emp\u00eacher de passer au peigne fin quelques \u00e9l\u00e9ments techniques et commerciaux de ces annonces. Comme d\u2019habitude avec ces lancements majeurs, on est face \u00e0 une v\u00e9ritable corne d\u2019abondance de nouveaut\u00e9s. Il faut plus de temps pour les analyser que pour toutes les annonces d\u2019Apple d\u2019une ann\u00e9e enti\u00e8re ! De nouveaux standards techniques font aussi leur apparition dont il faut comprendre les caract\u00e9ristiques, les \u00e9cosyst\u00e8mes et les usages (Wi-Fi AC4400, connexion 10 Gbits\/s en SFP+, HomePlug AV2, commande vocale\u2026).<\/p>\n<p>La Freebox Delta red\u00e9finit le haut de gamme dans le march\u00e9 des box en France et m\u00eame dans le monde. Cela rappelle la strat\u00e9gie d\u2019Apple qui fait inexorablement grimper son offre en gamme et augmente les prix en cons\u00e9quence. Cette mont\u00e9e en gamme et l\u2019usage, voir l\u2019abus, du \u201cbundling\u201d de services est une arme \u00e0 double tranchant comme nous allons le voir.<\/p>\n<p>Pour r\u00e9f\u00e9rence, les dossiers complets de Free sont t\u00e9l\u00e9chargeables pour la <a href=\"http:\/\/www.iliad.fr\/presse\/2018\/DP_Freebox_Delta_041218.pdf\">Freebox Delta<\/a> (30 pages) et la <a href=\"http:\/\/www.iliad.fr\/presse\/2018\/CP_Freebox_One_041218.pdf\">Freebox One<\/a> (9 pages). La premi\u00e8re est la version haut de gamme avec un serveur et un player et la seconde est une box tout en un d\u2019entr\u00e9e de gamme.<\/p>\n<p>Dans <a href=\"https:\/\/www.oezratty.net\/wordpress\/2010\/les-vrais-gens-et-le-marketing-de-free\/\">Les vrais gens et le marketing de Free<\/a> en 2010, j\u2019avais d\u00e9crit le mode de fonctionnement de la soci\u00e9t\u00e9. A-t-il \u00e9volu\u00e9 depuis ? Pas tant que cela. C\u2019est plut\u00f4t la position de Xavier Niel qui a chang\u00e9. Il est bien plus visible. Il s\u2019est engag\u00e9 \u00e0 financer l\u2019\u00e9cosyst\u00e8me de l\u2019innovation technologique en France avec l\u2019EEMI, 42, Kima puis Station F, ce qu\u2019aucun entrepreneur ou milliardaire fran\u00e7ais n\u2019a fait \u00e0 ce jour \u00e0 ce niveau d\u2019engagement. S\u2019est-il dilu\u00e9 ? Il semble que non. Il passe toujours autant de temps avec les \u00e9quipes de Free.<\/p>\n<p>Les \u00e9quipes techniques qui con\u00e7oivent la Freebox c\u00f4t\u00e9 mat\u00e9riel comme logiciel tiennent toujours dans un \u00e9tage de son si\u00e8ge \u00e0 Paris, donc moins d\u2019une centaine de personnes. Elles ne sont pas enti\u00e8rement seules puisqu\u2019elles travaillent avec une trentaine de partenaires technologiques, certains connus (Qualcomm, Devialet, Dolby, Somfy, Philips, Canal+, LeKiosk, Amazon), d\u2019autres, pas encore annonc\u00e9s. Xavier Niel pr\u00e9sente ses \u00e9quipes comme \u00e9tant les meilleurs du monde. C\u2019est \u00e9videmment exag\u00e9r\u00e9. Tous les patrons disent cela de leurs \u00e9quipes lorsqu\u2019ils en sont fiers. C\u2019est un bon moyen de les valoriser. Mais la performance est l\u00e0 : cr\u00e9er de telles box avec si peu d\u2019ing\u00e9nieurs et techniciens est une belle performance. Elle aboutit parfois \u00e0 faire quelques impasses c\u00f4t\u00e9 qualit\u00e9, surtout au moment du lancement et dans le logiciel mais le r\u00e9sultat reste remarquable. Et les autres op\u00e9rateurs ont aussi connu des probl\u00e8mes de qualit\u00e9 lors du lancement de leurs nouvelles box, qu\u2019elles soient r\u00e9alis\u00e9es avec des effectifs voisins de ceux de Free (SFR, Bouygues Telecom, avec peut-\u00eatre plus de sous-traitance, comme chez Wyplay chez le premier ou iFeelSmart chez le second) ou bien plus importants (Orange, avec ses \u00e9quipes de R&amp;D et ses filiales Softathome et Viaccess).<\/p>\n<p>C\u2019est donc parti pour un tour complet de l\u2019offre avec dans l\u2019ordre : le Freebox Delta Server, le Freebox Delta Player, les contenus, puis la Freebox One et enfin les questions de tarification.<\/p>\n<p><strong>Freebox Delta Server<\/strong><\/p>\n<p>Cette box serveur est la premi\u00e8re du march\u00e9 \u00e0 proposer une entr\u00e9e fibre \u00e0 10 Gbits\/s, en lieu et place du Gbits\/s d\u00e9j\u00e0 propos\u00e9 dans les box depuis la Freebox R\u00e9volution de d\u00e9but 2011. Elle comprend de nombreuses autres nouveaut\u00e9s que je vais d\u00e9tailler.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image.png\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image_thumb.png\" alt=\"image\" width=\"363\" height=\"230\" border=\"0\" \/><\/a><\/p>\n<p><u>10 Gbits\/s<\/u><\/p>\n<p>Xavier Niel expliquait au lancement comment ce d\u00e9bit allait changer la vie des utilisateurs, permettant de t\u00e9l\u00e9charger des contenus bien plus rapidement, notamment comparativement \u00e0 une fibre classique \u00e0 1 Gbits\/s. Cela concerne notamment les jeux en t\u00e9l\u00e9chargement ou les films propos\u00e9s \u00e9galement en t\u00e9l\u00e9chargement et qui peuvent \u00eatre tr\u00e8s lourds. Pour des usages professionnels, c\u2019est aussi tr\u00e8s utile pour transmettre des photos et des vid\u00e9os. Les Freebox sont aussi utilis\u00e9es par les TPE !<\/p>\n<p>Une telle box va probablement avoir un cycle de vie d\u2019au moins 5 \u00e0 8 ans. Il faut donc tenir compte des \u00e9volutions des usages que l\u2019on n\u2019anticipe pas forc\u00e9ment. Lorsque la Freebox R\u00e9volution a commenc\u00e9 \u00e0 \u00eatre distribu\u00e9e d\u00e9but 2011, ses ports 1 Gbits\/s \u00e9taient peu utilis\u00e9s tout comme la connectique fibre. Au gr\u00e9 des d\u00e9ploiements de la fibre, le 1 Gbits\/s est devenu pertinent. Aussi bien en d\u00e9bit qu\u2019au niveau du temps de latence qui est d\u2019\u00e0 peine quelques ms, ce qui ravit les joueurs. Le d\u00e9veloppement des usages num\u00e9riques dans les foyers justifie aussi ces d\u00e9bits. Surtout si la famille comprend un ou deux gros \u201cgamers\u201d.<\/p>\n<p>En pratique, cependant, peu de services en ligne offrent un tel d\u00e9bit par utilisateur au niveau de leurs serveurs et datacenters. D\u2019exp\u00e9rience, il est bien rare d\u2019avoir plus de 50 Mo\/s (480 Mbits\/s) en t\u00e9l\u00e9chargement sur un serveur donn\u00e9 avec une fibre \u00e0 1 Gbits\/s, m\u00eame aux heures creuses. Ce n\u2019est pas \u00e0 cause des infrastructures t\u00e9l\u00e9coms de Free mais plut\u00f4t de celles des sources de t\u00e9l\u00e9chargement. Nombre d\u2019h\u00e9bergeurs utilisent du \u201cthrottling\u201d pour limiter la bande passante utilis\u00e9e par chaque utilisateur Internet. Dans l\u2019offre de hosting la plus haut de gamme d\u2019Online.net, il est propos\u00e9 une liaison \u00e0 10 Gbits\/s pour un serveur d\u00e9di\u00e9. Un serveur pour plusieurs utilisateurs ! Un h\u00e9bergeur souhaitant servir ses utilisateurs avec du tr\u00e8s haut d\u00e9bit devra donc faire appel \u00e0 des offres en cloud solides pour tenir le choc de t\u00e9l\u00e9chargements \u00e0 10 Gbits\/s.<\/p>\n<p>Free devrait pratiquement limiter le d\u00e9bit en download \u00e0 8 Gbit\/s et en upload \u00e0 400 Mbit\/s. Cela permettra pour commencer d\u2019alimenter le serveur et ses disques. Les outils logiciels du serveur permettaient de d\u00e9clencher des sessions BitTorrent dans la Freebox R\u00e9volution. Je suppose que c&#8217;est toujours le cas dans la Delta.<\/p>\n<p>La Delta Server voit cependant loin et grand en connectique. Elle comprend un port optique pour l\u2019arriv\u00e9e de la fibre et un port SFP+ de 10 Gbits\/s en sortie qui permet d&#8217;\u00e9tablir, via un adaptateur, une liaison \u00e0 ce d\u00e9bit via un c\u00e2ble en cuivre ou une liaison optique. La conversion est r\u00e9alis\u00e9e dans la prise qui se branche sur le connecteur SFP+.<\/p>\n<p>Cette connectique est une premi\u00e8re dans une box grand public. Elle permet une connexion en 10G (raccourci pour 10 Gbits\/s) \u00e0 un desktop, un laptop, un switch et m\u00eame un NAS externe.\u00a0Les amateurs vont ainsi pouvoir constituer un r\u00e9seau local 10 Gbits\/s, la box supportant le routage et le NAT (mapping d&#8217;adresses IP entre celles du r\u00e9seau local et celles d&#8217;Internet) \u00e0 ce d\u00e9bit.<\/p>\n<p>Quatre autres ports r\u00e9seau sont des classiques RJ45 Ethernet \u00e0 1 Gbits\/s. Certains <a href=\"https:\/\/www.01net.com\/actualites\/qu-est-ce-que-la-freebox-delta-a-vraiment-dans-le-ventre-1581152.html\">articles<\/a> et <a href=\"https:\/\/www.lesnumeriques.com\/vie-du-net\/freebox-delta-one-pourquoi-free-renie-origines-n81327.html\">commentaires<\/a> ont l\u2019air de dire que ce port SFP+ ne sert qu\u2019\u00e0 la connexion au r\u00e9seau de Free et pas au r\u00e9seau local. Cela semble inexact. A quoi bon Free proposerait-il un d\u00e9bit 10G en entr\u00e9e s\u2019il n\u2019\u00e9tait pas exploitable dans le r\u00e9seau domestique ? Juste pour remplir le NAS ? En fait, Free confirme bien que ce port permet de cr\u00e9er son r\u00e9seau local 10 Gbits\/s.<\/p>\n<p>Pour g\u00e9rer son r\u00e9seau local \u00e0 10 Gbits\/s, il faudra en tout cas utiliser des c\u00e2bles et installation sp\u00e9cialis\u00e9s qui ne sont pas encore courants (exemple <em>ci-dessous<\/em>) et s\u2019\u00e9quiper de cartes r\u00e9seau 10 Gbits\/s PCI ou PCI Express pour un desktop, et \u00e0 des prix compris entre 100\u20ac et 250\u20ac (exemple chez <a href=\"https:\/\/www.amazon.fr\/Xg-c100c-Express-Gigabit-Transferts-Donn%C3%A9es\/dp\/B071JR2ZW8\/ref=sr_1_3?ie=UTF8&amp;qid=1544115908&amp;sr=8-3&amp;keywords=carte+r%C3%A9seau+PCI+10Gb\">Asus<\/a>). Si on veut connecter plusieurs \u00e9quipements, il faudra ajouter un switch ou routeur Wi-Fi 10 Gbits\/s utilisant ces prises et adaptateurs SFP+. Quelques-uns existent comme le <a href=\"https:\/\/www.amazon.fr\/NETGEAR-XR700-100EUS-Routeur-Nighthawk-Powered\/dp\/B07GZ138X8\/ref=sr_1_1?s=computers&amp;ie=UTF8&amp;qid=1544117281&amp;sr=1-1&amp;keywords=netgear+XR700\">Netgear XR700<\/a>, \u00e0 500\u20ac ou le <a href=\"https:\/\/www.amazon.fr\/s\/ref=nb_sb_noss?__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;url=search-alias%3Daps&amp;field-keywords=Nighthawk+X10+AD7200+\">Nighthawk X10 AD7200 R9000<\/a> qui est \u00e0 environ 420\u20ac. Le routeur <a href=\"https:\/\/www.amazon.fr\/TP-Link-T1700G-28TQ-Gigabit-Fanless-Stackable\/dp\/B01CHP5IAC\/ref=sr_1_4?ie=UTF8&amp;qid=1544134985&amp;sr=8-4&amp;keywords=switch+10G+SFP%2B\">TP-Link T1700G-28TQ<\/a> contient quatre ports SFP+ \u00e0 10 Gbits\/s et 24 ports Ethernet RJ45 classiques \u00e0 1 Gbits\/s, pour 270\u20ac.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Calbles-SFPPlus.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; margin: 10px 0px 10px 10px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Calbles SFPPlus\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Calbles-SFPPlus_thumb.jpg\" alt=\"Calbles SFPPlus\" width=\"240\" height=\"204\" border=\"0\" \/><\/a><\/p>\n<p>Il existe aussi des routeurs 10 GBits\/s dot\u00e9s de prises RJ45 10 Gbits\/s qui utilisent des c\u00e2bles Cat6, Cat6A et Cat7. Plus le chiffre est \u00e9lev\u00e9, plus le d\u00e9bit acceptable l\u2019est tout comme la distance du c\u00e2ble. Le routeur Netgear GS110EMX dispose ainsi de deux prises RJ45 en 10 Gbits\/s et 8 prises RJ45 en 1 Gbits\/s mais pas de port SFP+, pour 243\u20ac. Pour connecter ce routeur \u00e0 la Freebox Delta, on pourra utiliser un adaptateur SFP+\/RJ45 plac\u00e9 sur le port SFP+ de la Freebox Delta Server (<a href=\"https:\/\/www.amazon.fr\/Transceiver-10GBase-T-30-m%C3%A8tres-Ubiquiti-Compatible\/dp\/B01M8O3MAL\">exemple<\/a>, <em>ci-dessous<\/em>), puis utiliser un c\u00e2ble RJ45 Cat6 ou plus pour relier la box au routeur. Un tel adaptateur co\u00fbte au minimum 100\u20ac. Les c\u00e2bles Cat6 et 7 sont de leur c\u00f4t\u00e9 abordables.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Adaptateur-SFP-et-RJ45.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; margin: 10px 0px 10px 10px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Adaptateur SFP et RJ45\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Adaptateur-SFP-et-RJ45_thumb.jpg\" alt=\"Adaptateur SFP et RJ45\" width=\"280\" height=\"153\" border=\"0\" \/><\/a><\/p>\n<p>Voici donc \u00e0 quoi ressemblent ces routeurs avec en haut le Netgear avec des RJ45 10G et en-dessous, un TP-Link avec 4 prises SFP+.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/2018\/le-pari-haut-de-gamme-de-free\/routeurs-10g\/\" rel=\"attachment wp-att-16959\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16959\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/Routeurs-10G.jpg\" alt=\"\" width=\"497\" height=\"336\" srcset=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/Routeurs-10G.jpg 1382w, https:\/\/www.oezratty.net\/wordpress\/wp-content\/Routeurs-10G-300x203.jpg 300w, https:\/\/www.oezratty.net\/wordpress\/wp-content\/Routeurs-10G-768x520.jpg 768w, https:\/\/www.oezratty.net\/wordpress\/wp-content\/Routeurs-10G-1024x693.jpg 1024w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" \/><\/a><\/p>\n<p>Enfin, si vous souhaitez connecter votre laptop, vous pourrez passer par un adaptateur Thunderbolt \u2013 10G Ethernet, mais ils ne sont visiblement pas encore nombreux.<\/p>\n<p>Bref, tout cela pour dire que le passage au 10 Gbits\/s dans son r\u00e9seau domestique n\u2019est pas imm\u00e9diat ni gratuit. Mais cela permet de voir loin et de se cr\u00e9er si besoin est un r\u00e9seau local de comp\u00e9tition. D\u2019ici quelque temps, certains amateurs et professionnels en tireront certainement partie. Je ne serais d\u2019ailleurs pas \u00e9tonn\u00e9 de voir une connectique 10G commencer \u00e0 fleurir au CES 2019.<\/p>\n<p>Il faut enfin noter que la mise en place de cette offre \u00e0 10 Gbits a n\u00e9cessit\u00e9 une mise \u00e0 jour de certains \u00e9quipements dans les NRO de Free (N\u0153uds de Raccordements Optiques) pour le brassage et le multiplexage des fibres, sans compter les interconnexions avec d\u2019autres op\u00e9rateurs comme Orange.<\/p>\n<p>Enfin, pr\u00e9cisons que si cette offre \u00e0 10 Gbits\/s est une premi\u00e8re pour un op\u00e9rateur grand public, elle existe d\u00e9j\u00e0 ailleurs dans le monde et en France, chez <strong>Netalis<\/strong>, qui cible les professionnels (<a href=\"https:\/\/www.nextinpact.com\/news\/107220-une-connexion-internet-a-10-gbs-offres-existent-deja-y-compris-en-france.htm?fbclid=IwAR1P4BRKhIvhlSV0SJrwWRDLENx-wr7erNjFRQIZKEEXysSfleFD2M63-Gg\">source<\/a> et <a href=\"https:\/\/www.netalis.fr\/2018\/10\/09\/fibre-optique-netalis-lance-le-ftth-pro-10-gbit-s-pour-les-tpe-et-pme\/?fbclid=IwAR2t5VENhRzqcZ54eFISXTpYmPTyk3gJH_XUqk4Wt4L57dAUSLidl-cBuec\">information de l&#8217;op\u00e9rateur<\/a>). Autre mise en perspective, le constructeur chinois <strong>Byton<\/strong> annon\u00e7ait au CES 2018 que ses v\u00e9hicules seraient \u00e9quip\u00e9s d&#8217;une liaison sans fil 5G \u00e0 10 Gbits\/s. Une annonce qu&#8217;il faut \u00e9videmment prendre avec des pincettes car ce d\u00e9bit est plus difficile \u00e0 assurer, autant dans les zones denses et donc encombr\u00e9es d&#8217;utilisateurs que dans les zones faiblement denses, o\u00f9 le maillage des antennes en ondes millim\u00e9triques ne seront pas suffisantes pour assurer un tel d\u00e9bit. Enfin, le 10 Gbits\/s est aussi support\u00e9 par le nouveau standard Wi-Fi 802.11 ay qui est notamment int\u00e9gr\u00e9 dans le chipset <strong>Qualcomm<\/strong> Snapdragon 855 pour smartphones 5G annonc\u00e9 cette m\u00eame semaine.<\/p>\n<p><u>NAS<\/u><\/p>\n<p>La Freebox Delta Server devient un v\u00e9ritable syst\u00e8me de stockage centralis\u00e9 pour le foyer, un NAS (Network Access Storage). Il va pouvoir remplacer des NAS d\u00e9di\u00e9s qui valent souvent aux alentours de 200 \u00e0 1000\u20ac selon les capacit\u00e9s.<\/p>\n<p>La box est fournie avec un disque dur de 1 To. Elle comprend en tout quatre slots de disques, permettant de consolider jusqu\u2019\u00e0 20 To de stockage et en architecture RAID de son choix pour g\u00e9rer la tol\u00e9rance de pannes. Ces slots sont accessibles par une trappe au dessous de la box comme l\u2019a pr\u00e9sent\u00e9 <a href=\"https:\/\/www.clubic.com\/connexion-internet\/fai-free-box-freebox\/freebox-v7\/article-848218-1-freebox-delta-design-connectique-accessoires-photos-exclusives.html\">Clubic<\/a>.<\/p>\n<p>Les slots sont au format 2,5 pouces et en interface SATA3 classique, utilis\u00e9e aussi bien par des disques durs ou des SSD de ce format. Notamment par les fameux Samsung EVO 850, qui vont jusqu\u2019\u00e0 2 To (pour environ 440\u20ac). En disque dur, cette capacit\u00e9 en 2,5 pouces tombe \u00e0 moins de 70\u20ac.<\/p>\n<p>Les connecteurs M.2 utilis\u00e9s dans les laptops haut de gamme r\u00e9cents sont trop rares, et ne fonctionnent qu\u2019avec des SSD pour l\u2019instant. Surtout pour la variante PCIe\/MVNe. Les d\u00e9bits d\u2019un SSD en SATA3 vont jusqu\u2019\u00e0 6 Gbits\/s ou 750 Mo\/s th\u00e9oriques. En PCIe\/MVNe, ils atteignent 1,4 Go\/s !<\/p>\n<p>On trouve en effet des disques durs au format 2,5 pouces atteignant 5 To. Le <a href=\"https:\/\/www.amazon.fr\/SEAGATE-st5000lm000-Barracuda-Disque-Interne-128-Mo\/dp\/B01LXO31IZ\/ref=sr_1_5?ie=UTF8&amp;qid=1544119546&amp;sr=8-5&amp;keywords=disque+dur+2%2C5+pouces+5+To\">Seagate BarraCuda 5 To<\/a> co\u00fbte 173\u20ac actuellement. De mani\u00e8re courante sous Windows, le d\u00e9bit d\u2019un SSD en SATA est situ\u00e9 aux alentours de 325 Mo\/s, donc, 2,6 Gbits\/s. Ceci justifie donc une connectique 10G qui permet d\u2019avoir un d\u00e9bit de r\u00e9seau local sup\u00e9rieur \u00e0 celui du stockage.<\/p>\n<p>Le support du 10 Gbits\/s prend donc tout son sens avec un NAS si on peut le g\u00e9rer de bout en bout avec les PC qui interagissent avec, notamment pour faire des sauvegardes et g\u00e9rer de gros fichiers. Ce, malgr\u00e9 les limites pratiques de la connectivit\u00e9 10G avec Internet. Evidemment, modulo tout l\u2019\u00e9quipement n\u00e9cessaire que nous venons de voir dans la partie pr\u00e9c\u00e9dente, mais dont les prix vont certainement baisser dans les ann\u00e9es \u00e0 venir.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Freebox-Delta-Server-Dos.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; margin: 10px 0px 10px 10px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Freebox Delta Server Dos\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Freebox-Delta-Server-Dos_thumb.jpg\" alt=\"Freebox Delta Server Dos\" width=\"454\" height=\"199\" border=\"0\" \/><\/a><\/p>\n<p>Je note que, d&#8217;une certaine mani\u00e8re, l&#8217;approche de Free sur le serveur est diam\u00e9tralement oppos\u00e9e \u00e0 celle d&#8217;Orange qui pour sa derni\u00e8re box a beaucoup mis\u00e9 sur la virtualisation et sur le d\u00e9port de fonctions utilisateurs dans les serveurs de l&#8217;op\u00e9rateur. M\u00eame si certains geeks n&#8217;appr\u00e9cient pas l&#8217;augmentation des prix de la Freebox, ils appr\u00e9cieront tout de m\u00eame la latitude que cela leur donne pour constituer un r\u00e9seau domestique de qualit\u00e9.<\/p>\n<p>Ils pourront par exemple ajouter un routeur 10G avec au moins quatre ports et le relier \u00e0 un NAS en 10G et comprenant des slots pour SSD en M.2 \/ MVNe \/ PCIe. Par un exemple un <strong>Synology\u00a0<\/strong><span class=\"name\">DS1517+ avec une carte\u00a0M2D18 sur laquelle installer un SSD de 2 To avec un temps d&#8217;acc\u00e8s de plus de 1 Go\/s. Ou encore un <strong>QNAP<\/strong> TVS-872XT (Core i5 avec 16 Go de RAM, connectique 10G en RJ45) qui dispose de deux slots pour SSD M.2 PCIe NVMe en plus de ses slots SATA classiques. Une version \u00e0 112 To (SATA) avec les deux slots dispos pour des SSD M.2 est \u00e0 5500\u20ac ! De quoi \u00e9quiper une belle agence de production vid\u00e9o.<\/span><\/p>\n<p><u>DSL+4G<\/u><\/p>\n<p>Le serveur permet aussi l\u2019agr\u00e9gation automatique de l\u2019ADSL et de la 4G, permettant d\u2019augmenter le d\u00e9bit disponible pour les abonn\u00e9s passant par le cuivre. La bande passante DSL est utilis\u00e9e en priorit\u00e9, avant que le boost de la 4G soit d\u00e9clench\u00e9 en cas de besoin. La r\u00e9ception de la TV (IPTV) passe uniquement par la liaison cuivre et le DSL.<\/p>\n<p>Evidemment, le d\u00e9bit additionnel procur\u00e9 par la 4G d\u00e9pend de la situation g\u00e9ographique du client. En moyenne, cependant, il y a souvent pas mal de chances que la 4G d\u00e9multiplie le d\u00e9but d\u2019un ADSL \u00e0 plus de 2 \u00e0 3 km des DSLAM, sauf dans les zones blanches de la r\u00e9ception de la 4G qui existent encore. Une bonne 4G peut monter \u00e0 20-50 Mbits\/s, vs un ADSL poussif qui peut \u00eatre situ\u00e9 entre 4 et 10 Mbits\/s. Des cartes de couverture et de d\u00e9bit par op\u00e9rateurs sont disponibles en ligne pour se faire une id\u00e9e de la question, notamment chez Nperf qui fournit aussi le logiciel Speedtest de test de vitesse d\u2019acc\u00e8s Internet fixe et mobile. <em>Ci-dessous<\/em>, une carte de r\u00e9ception de Free Mobile en Bretagne (<a href=\"https:\/\/www.nperf.com\/en\/map\/FR\/-\/3.Free\/download\/?ll=48.087253543853336&amp;lg=-2.2741702571511273&amp;zoom=8\">source<\/a>).<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Bretagne-couverture-Free-debit.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Bretagne couverture Free debit\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Bretagne-couverture-Free-debit_thumb.jpg\" alt=\"Bretagne couverture Free debit\" width=\"490\" height=\"247\" border=\"0\" \/><\/a><\/p>\n<p>On peut donc tabler sur une multiplication du d\u00e9bit disponible par 2 \u00e0 10 selon les cas de figure. Free annonce que le d\u00e9bit pourra atteindre 200 Mbit\/s en download et 60 Mbit\/s en upload, un cas de figure qui sera certainement tr\u00e8s rare !<\/p>\n<p>Un d\u00e9tail d\u2019importance : quelle partie du mat\u00e9riel du serveur g\u00e8re la 4G ? Le Snapdragon 835 g\u00e8re tr\u00e8s bien cela, mais il est dans le Player ! La fonctionnalit\u00e9 est en fait g\u00e9r\u00e9e par un modem qui est int\u00e9gr\u00e9 dans le serveur et qui doit \u00eatre coupl\u00e9 \u00e0 une antenne. Le client n\u2019a pas \u00e0 g\u00e9rer son abonnement 4G. C\u2019est compris dans la box. Une limite de 250 Go par mois a \u00e9t\u00e9 annonc\u00e9e. Il y a peu de chances qu&#8217;elle soit atteinte car la 4G n&#8217;est utilis\u00e9e qu&#8217;en cr\u00eate lorsque le d\u00e9bit n\u00e9cessaire d\u00e9passe celui qui est fourni par la liaison DSL (ADSL2+ ou VDSL2). Et les contenus en streaming n&#8217;utilisent pas la 4G. 8 Go de t\u00e9l\u00e9chargement suppl\u00e9mentaire par jour, c&#8217;est d\u00e9j\u00e0 pas mal !<\/p>\n<p><u>Courant porteur<\/u><\/p>\n<p>Des Freeplugs au standard <strong>HomePlug<\/strong> AV2 MIMO de nouvelle g\u00e9n\u00e9ration \u00e0 1 Gbits\/s sont aussi int\u00e9gr\u00e9es. Elles servent surtout \u00e0 relier le serveur au player. La prise HomePlug int\u00e8gre l\u2019alimentation, ce qui rend les branchements plus faciles.<\/p>\n<p>Le HomePlug AV2 date de 2012. Il permet un d\u00e9bit physique de plus de 1 Gbits\/s mais cela se traduirait par un d\u00e9bit r\u00e9el aux alentours de 500 Gbits\/s. Ce qui soit dit en passant est largement suffisant pour diffuser de la 4K HDR en streaming au Player. Donc, <em>no soucy<\/em>.<\/p>\n<p><u>Wi-Fi ac<\/u><\/p>\n<p>La borne Wi-Fi int\u00e9gr\u00e9e dans le serveur est tri-bandes (une bande 2,4 GHz et deux bandes 5 GHz) et le Wi-Fi ac est MU-MIMO. Free annonce un d\u00e9bit total de 4,4 Go\/s, le meilleur niveau disponible aujourd\u2019hui. C\u2019est visiblement l\u2019\u00e9quivalent d\u2019une paire de routeurs <strong>DLink<\/strong> Velop WiFi Multiroom AC4400. Ce d\u00e9bit n\u2019est pas accessible pour un seul device. La bande passante maximum th\u00e9orique pour un device sera celle d\u2019une bande de 5 GHz, soit 867 Mbits\/s. Le d\u00e9bit th\u00e9orique de 4,4 Gbits\/s \u00e9quivaut \u00e0 2 fois (400 Mbits\/s pour la bande des 2,4 Ghz et deux bandes de 5 GHz \u00e0 867 Mbits\/s).<\/p>\n<p>On note aussi des fonctions permettant de configurer plus rapidement son Wi-fi pour ses smartphones, tablettes et autres, notamment via une borne NFC int\u00e9gr\u00e9e. Par contre, contrairement aux routeurs Wi-Fi r\u00e9cents, la box ne comprend pas d\u2019antennes ext\u00e9rieures. On peut esp\u00e9rer que ses antennes sont bien dispos\u00e9es \u00e0 l\u2019int\u00e9rieur de la bo\u00eete pour maximiser la port\u00e9e du Wi-Fi. La documentation ne pr\u00e9cise pas le nombre d\u2019antennes utilis\u00e9es. Il faudra attendre que les geeks d\u00e9montent leur premi\u00e8re Freebox Delta pour en savoir plus.<\/p>\n<p><u>Centrale d\u2019alarme<\/u><\/p>\n<p>S\u2019y ajoute une connectivit\u00e9 <strong>Sigfox<\/strong> associ\u00e9e \u00e0 un syst\u00e8me d\u2019alarme bas\u00e9 sur un capteur d\u2019ouverture, un d\u00e9tecteur de mouvements et une cam\u00e9ra de surveillance \u00e0 vision nocturne qui analyse aussi les bruits anormaux. Sa r\u00e9solution est de 720p ce qui correspond aujourd\u2019hui \u00e0 l\u2019entr\u00e9e de gamme. Le serveur comprend aussi une sir\u00e8ne ainsi qu\u2019une batterie pour \u00eatre autonome quelques temps en cas de coupure de courant ! C\u2019est compl\u00e9t\u00e9 par une petite t\u00e9l\u00e9commande (<em>ci-dessous<\/em> \u00e0 gauche). On peut compl\u00e9ter son installation si besoin est avec d\u2019autres d\u00e9tecteurs d&#8217;ouverture \u00e0 20 \u20ac l\u2019unit\u00e9, d\u00e9tecteurs de mouvement \u00e0 30 \u20ac et cam\u00e9ras \u00e0 40\u20ac, qui sont des prix tout \u00e0 fait raisonnables.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Pack-Securite.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; margin: 10px 0px 10px 10px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Pack Securite\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Pack-Securite_thumb.jpg\" alt=\"Pack Securite\" width=\"510\" height=\"204\" border=\"0\" \/><\/a><\/p>\n<p>Un service de t\u00e9l\u00e9surveillance est propos\u00e9 en option \u00e0 2\u20ac par mois avec d\u00e9placement d\u2019un gardien en cas d\u2019alerte inopin\u00e9e jusqu\u2019\u00e0 deux interventions par an, avec un gardiennage cons\u00e9cutif \u00e0 un incident pouvant aller jusqu\u2019\u00e0 24h. Les interventions suppl\u00e9mentaires, sans gardiennage, sont factur\u00e9es 120\u20ac TTC ce qui est correct. Free se positionne ici en concurrence directe avec des acteurs tels que <strong>Securitas Direct<\/strong> dont les abonnements sont compris entre 30 et 50\u20ac par mois et n\u00e9cessitent l\u2019installation d\u2019un mat\u00e9riel d\u00e9di\u00e9.<\/p>\n<p>Les interventions sont en fait r\u00e9alis\u00e9es par des agents de s\u00e9curit\u00e9 missionn\u00e9s par le groupe d\u2019assurances <strong>Axa<\/strong>. En fait, ce dernier fait appel \u00e0 un sous-traitant, <a href=\"https:\/\/www.protection24.com\/\">Protection 24<\/a> pour g\u00e9rer ce service (<a href=\"https:\/\/www.axa.fr\/assurance-habitation\/telesurveillance.html\">source<\/a>). Ce dernier fait partie du groupe BNP-Paribas. Et Axa est partenaire de <strong>Somfy<\/strong>, lui-m\u00eame support\u00e9 par la Freebox Delta. Tout se rejoint ! Dans ce <a href=\"https:\/\/www.capital.fr\/immobilier\/telesurveillance-les-meilleures-offres-pour-securiser-votre-logement-1194175\">classement de Capital<\/a> de soci\u00e9t\u00e9s de t\u00e9l\u00e9surveillance datant de 2016, les offres d\u2019Axa et de BNP-Paribas \u00e9taient tr\u00e8s bien not\u00e9es, ce qui est de bon augure.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Axa-et-P24-Protection.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; margin: 10px 0px 10px 10px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Axa et P24 Protection\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Axa-et-P24-Protection_thumb.jpg\" alt=\"Axa et P24 Protection\" width=\"510\" height=\"289\" border=\"0\" \/><\/a><\/p>\n<p>Pour la petite histoire, il y a quelques ann\u00e9es, j\u2019avais not\u00e9 une annonce pass\u00e9e un peu inaper\u00e7ue associant Sigfox et Canal+. Ce dernier devait int\u00e9grer une connectivit\u00e9 Sigfox dans ses box pour faciliter leur support technique, notamment pour les boxes reli\u00e9es au satellite et sans canal retour dans les zones blanches (mal desservies en ADSL). Visiblement, Canal+ n\u2019a pas concr\u00e9tis\u00e9 cette annonce. Il faut dire que leur management technique a subit des chamboulements s\u00e9rieux avec l\u2019arriv\u00e9e de Vincent Bollor\u00e9 au contr\u00f4le de Canal+ en 2015.<\/p>\n<p>L\u2019int\u00e9gration de Sigfox dans l\u2019offre de Free est une bonne nouvelle pour le Toulousain qui a bien besoin de d\u00e9ploiements en volume de sa technologie de r\u00e9seau M2M.<\/p>\n<p>On peut esp\u00e9rer que Free va utiliser cette liaison M2M pour autre chose que la centrale de surveillance, notamment pour le support technique des box. Reste \u00e0 savoir si le protocole de Sigfox permet de transmettre suffisamment d&#8217;informations pour r\u00e9pondre \u00e0 ce besoin.<\/p>\n<p><u>Processeur<\/u><\/p>\n<p>Le Freebox Delta Server est \u00e9quip\u00e9 d\u2019un chipset quad-core ARMv8 Cortex A72 d\u2019origine non pr\u00e9cis\u00e9e, peut-\u00eatre Broadcom, avec 2 Go de m\u00e9moire. Il faut au moins cela pour g\u00e9rer tous les services int\u00e9gr\u00e9s dans la box. Ce genre de processeur est similaire \u00e0 ceux que l\u2019on trouve dans les routeurs Wi-Fi haut de gamme. Notons enfin que la connectique comprend aussi deux ports USB-C et un port USB 3.0.<\/p>\n<p><strong>Freebox Delta Player<\/strong><\/p>\n<p>Sa forme a \u00e9t\u00e9 con\u00e7ue par le designer anglais Jasper Morrison. Exit donc Philippe Starck qui \u00e9tait aux manettes de la Freebox R\u00e9volution. Le r\u00e9sultat est\u2026 embarrassant. Le Player est particuli\u00e8rement encombrant, en raison de sa fonction d\u2019enceinte multicanal. Mais le design est sobre. Par contre, il va falloir trouver de la place pour l\u2019installer. Il n\u2019est pas indispensable de le placer sous la TV dans l\u2019axe de vision. Sa projection sonore \u00e0 360\u00b0 devrait permettre de l\u2019installer sur le c\u00f4t\u00e9. Il va juste falloir, comme d\u2019habitude, int\u00e9grer l\u2019ensemble du c\u00e2blage qui l\u2019alimente avec au minimum le secteur via la Freeplug et la sortie HDMI pour sa TV ou son vid\u00e9o projecteur.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image15.png\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image15_thumb.png\" alt=\"image\" width=\"299\" height=\"195\" border=\"0\" \/><\/a><\/p>\n<p><u>Processeur<\/u><\/p>\n<p>Le chipset int\u00e9gr\u00e9 est un Qualcomm Snapdragon APQ8098, en fait, un Snapdragon 835, son petit nom \u201cmarketing\u201d plus facile \u00e0 retenir. C\u2019est un octo-c\u0153urs avec quatre c\u0153urs rapides et quatre c\u0153urs plus lents et \u00e0 basse consommation, dans une architecture d\u00e9nomm\u00e9e chez Arm \u201cBIGlittle\u201d. Il est compl\u00e9t\u00e9 d\u2019un GPU Adreno 540 qui comprend notamment un d\u00e9codeur de vid\u00e9o natif UHD au format HDR-10 (high dynamic range). Il est grav\u00e9 en 10 nm chez TSMC.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Qualcomm-Snapdragon-835-Block-Diagra.png\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Qualcomm Snapdragon 835 Block Diagram\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Qualcomm-Snapdragon-835-Block-Diagra_thumb.png\" alt=\"Qualcomm Snapdragon 835 Block Diagram\" width=\"398\" height=\"342\" border=\"0\" \/><\/a><\/p>\n<p>Le Snapdragon 835 a \u00e9t\u00e9 lanc\u00e9 au CES 2017. Il est surtout utilis\u00e9 dans les smartphones haut de gamme. Sa puissance est au rendez-vous pour alimenter une set-top-box 4K et HDR.<\/p>\n<p>C\u00f4t\u00e9 audio, il supporte nativement les codecs audio DSD (DSD64\/DSD128) et surtout, le PCM jusqu\u2019au 384kHz \/ 32 bits. Ce qui permet d\u2019\u00e9couter de la musique HiRes en qualit\u00e9 maximale. Sachant que le service Qobuz support\u00e9 par la Freebox va jusqu\u2019au\u00a0 192 KHz \/ 24 bits. Le chipset 835 peut-\u00eatre compl\u00e9t\u00e9 par un module Aqstic pour la reconnaissance de la parole en local, mais rien ne dit qu\u2019il est int\u00e9gr\u00e9 dans la Freebox Delta Player. J\u2019ai toujours \u00e9t\u00e9 \u00e9tonn\u00e9 par le manque de promotion de cette fonctionnalit\u00e9 par les constructeurs de smartphones. Free n\u2019y fait pas exception. Ils n\u2019ont pas parl\u00e9 d\u2019audio HiRes lors du lancement ! Free pr\u00e9cise cependant que le codec FLAC est support\u00e9.<\/p>\n<p>La version la plus r\u00e9cente des chipsets mobiles de Qualcomm est le Snapdragon 855, annonc\u00e9e en ao\u00fbt 2018. Il int\u00e8gre le modem Qualcomm X24 et le X50, le rendant pr\u00eat pour la 5G dans les bandes millim\u00e9triques (au-del\u00e0 de 5 GHz). Ce chipset \u00e9quipera peut-\u00eatre une version ult\u00e9rieure du Freebox Delta Player.<\/p>\n<p><u>Devialet Inside<\/u><\/p>\n<p>C\u00f4t\u00e9 player, la fonction la plus remarqu\u00e9e est l\u2019int\u00e9gration d\u2019un syst\u00e8me audio multi-canal originaire de Devialet, avec 6 haut-parleurs, trois de basses \u00e0 fort d\u00e9battement et trois de m\u00e9diums\/aigus. La forme triangulaire de la box permet une diffusion sous tous les angles dans la pi\u00e8ce. Elle est con\u00e7ue de mani\u00e8re \u00e0 reproduire un son multicanal 5.1 par r\u00e9flexion sur les murs, comme le font les barres d\u2019enceintes pour TV depuis plus de 10 ans. Elle devrait supporter Dolby Atmos d\u00e9but 2019.<\/p>\n<p>En gros, le Player est pour ce qui est de l\u2019audio une sorte de Devialet Phantom aplatie et moins puissante et pour moins cher (480\u20ac vs 1000\u20ac pour la Phantom la moins ch\u00e8re, la Reactor qui fait 900W max).<\/p>\n<p>D\u2019ailleurs, la documentation de l\u2019engin ne pr\u00e9cise pas du tout la puissance de son amplificateur. N\u2019est pas indiqu\u00e9e non plus si le syst\u00e8me dispose d\u2019un syst\u00e8me d\u2019auto-\u00e9galisation du son \u00e0 la position d\u2019\u00e9coute. Pour ce faire, il faudrait disposer d\u2019un microphone d\u00e9di\u00e9 comme ceux qui sont souvent fournis avec les amplificateurs audio-vid\u00e9o multicanal. Le micro de la t\u00e9l\u00e9commande tactile n\u2019a pas l\u2019air de pouvoir servir \u00e0 cela.<\/p>\n<p>La box int\u00e8gre la fonction AVL (Adaptative Volume Level) qui ajuste le niveau sonore en fonction des sc\u00e8nes d\u2019un film et SAM qui optimise le son pour ses morceaux pr\u00e9f\u00e9r\u00e9s sans qu\u2019il soit pr\u00e9cis\u00e9 \u00e0 quoi cela correspond. Elles proviennent toutes les deux de Devialet. Elles m\u00e9riteraient d\u2019\u00eatre d\u00e9crites autrement que dans un langage marketing un peu trop flou.<\/p>\n<p>Xavier Niel avait investi ses propres deniers dans Devialet en 2012 puis en 2015. Je l\u2019avais interrog\u00e9 \u00e0 l\u2019\u00e9poque sur ce qu\u2019il envisageait comme avenir pour cette startup. Il avait surtout en t\u00eate de d\u00e9mocratiser la qualit\u00e9 du son Devialet qui au d\u00e9part \u00e9tait disponible uniquement via un amplificateur haut de gamme \u00e0 plus de 20K\u20ac. Aujourd\u2019hui, leur haut de gamme est le 1000 Pro, \u00e0 27K\u20ac avec 1000 Watts par canal en st\u00e9r\u00e9o. Le son Devialet s\u2019appuie sur leur technologie ADH qui associe amplificateur num\u00e9rique et analogique et assure une excellente fid\u00e9lit\u00e9 du son et une tr\u00e8s faible distorsion. La Freebox a \u00e9t\u00e9 visiblement un moyen d\u2019aller dans le sens de cette d\u00e9mocratisation d\u2019un son de qualit\u00e9. C\u2019\u00e9tait bien vu \u00e0 l\u2019\u00e9poque et cela le reste aujourd&#8217;hui !<\/p>\n<p>D\u2019ailleurs, la Freebox Delta n\u2019est pas premi\u00e8re box \u00e0 utiliser la technologie Devialet puisque ce dernier avait d\u00e9j\u00e0 con\u00e7u la Soundbox pour l\u2019op\u00e9rateur <strong>Sky<\/strong> au Royaume Uni. La Soundbox ressemble plus \u00e0 une barre de son (<em>ci-dessous<\/em>). Elle comprend 9 haut-parleurs, dont 6 boomers de 7,5 cm et 3 haut-parleurs large bande de 5 cm.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Devialet-SoundBox-Sky.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; margin: 10px 0px 10px 10px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Devialet SoundBox Sky\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Devialet-SoundBox-Sky_thumb.jpg\" alt=\"Devialet SoundBox Sky\" width=\"421\" height=\"393\" border=\"0\" \/><\/a><\/p>\n<p>La Soundbox affiche une puissance de 140 W. Elle est commercialis\u00e9e environ 280\u20ac aux abonn\u00e9s de Sky et 890\u20ac aux autres clients. Cette puissance donne une indication de celle qui doit \u00eatre fournie dans le Freebox Delta Player. A noter qu\u2019une puissance n\u2019a de sens que si elle est associ\u00e9e \u00e0 une indication de distorsion harmonique totale (DHT). Plus cette derni\u00e8re est basse, mieux c\u2019est. Et elle est tr\u00e8s basse chez Devialet, tout du moins du c\u00f4t\u00e9 de l\u2019amplification.<\/p>\n<p><u>Vid\u00e9o et audio<\/u><\/p>\n<p>La vid\u00e9o support\u00e9e par le Player est \u00e9videmment UHD, soit quatre fois plus de pixels que le Full HD, soient 2160&#215;3840 pixels en ratio 16\/9. Sachant que la v\u00e9ritable 4K du cin\u00e9ma, li\u00e9e au standard DCI-4K, est de r\u00e9solution 2160&#215;4096 pixels, pour respecter le format 1\/1,89 des salles de cin\u00e9ma (hors Panavision et Cinemascope). L\u2019appellation de 4K dans la TV est un abus de langage mais il est courant.<\/p>\n<p>L\u2019affichage de vid\u00e9o en haute dynamique de luminosit\u00e9 HDR est aussi support\u00e9 avec le support du format HDR-10 mais pas encore de Dolby Vision pour l\u2019instant sachant que ce standard propri\u00e9taire HDR de Dolby pourra probablement \u00eatre ajout\u00e9 ult\u00e9rieurement par logiciel. Il ne semble pas qu\u2019il faille qu\u2019il soit nativement int\u00e9gr\u00e9 par le chipset pour \u00eatre support\u00e9.<\/p>\n<p>Les cha\u00eenes de TV sont diffus\u00e9es et r\u00e9ceptionn\u00e9es en HD+ \u00e0 15 Mbits\/s, le meilleur d\u00e9bit \u00e0 ce jour, lorsque la connexion cuivre le permet, et bien \u00e9videmment, dans le cas d\u2019une connexion fibre. Jusqu\u2019\u00e0 pr\u00e9sent, les cha\u00eenes en Full HD \u00e9taient souvent diffus\u00e9es avec un d\u00e9bit de 6 Mbits\/s. Il y a deux ans, Orange annon\u00e7ait le support de Netflix en UHD avec un d\u00e9bit de 13 Mbits\/s dans <a href=\"https:\/\/www.oezratty.net\/wordpress\/2016\/nouvelle-livebox-orange\/\">sa nouvelle Livebox<\/a>. L\u00e0, on a de la HD pour plus que cela. Par contre, le d\u00e9bit de diffusion des deux cha\u00eenes en UHD n\u2019a pas \u00e9t\u00e9 pr\u00e9cis\u00e9 par Free. Tout comme celui des contenus UHD propos\u00e9s ailleurs en VOD, SVOD et replay.<\/p>\n<p><u>T\u00e9l\u00e9commandes<\/u><\/p>\n<p>Deux t\u00e9l\u00e9commandes sont propos\u00e9es, dont une tactile et une autre classique. Il semble la premi\u00e8re ne fasse pas l\u2019unanimit\u00e9. Elle est tactile comme l\u2019\u00e9taient les \u00e9crans de <em>feature phone <\/em>pr\u00e9-smartphones \u00e0 matrices r\u00e9sistives. Il faut appuyer fort pour d\u00e9clencher la fonction correspondante. Ce qui est normal car cela permet d\u2019\u00e9viter les changements intempestifs de cha\u00eenes TV. Cette t\u00e9l\u00e9commande ajoute un retour haptique et comprend un \u00e9cran permettant l&#8217;affichage de menus contextuels (<a href=\"https:\/\/www.universfreebox.com\/article\/47593\/Decouvrez-la-procedure-de-demarrage-de-la-Freebox-Delta-et-l-association-des-telecommandes\">d\u00e9tails<\/a>). Les deux t\u00e9l\u00e9commandes sont \u00e9quip\u00e9es d\u2019un micro pour la commande vocale.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Telecommande-classique.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Telecommande classique\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Telecommande-classique_thumb.jpg\" alt=\"Telecommande classique\" width=\"79\" height=\"244\" border=\"0\" \/><\/a>\u00a0<a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Telecommande-tactile.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Telecommande tactile\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Telecommande-tactile_thumb.jpg\" alt=\"Telecommande tactile\" width=\"73\" height=\"244\" border=\"0\" \/><\/a><\/p>\n<p>A terme, il ne restera plus qu\u2019une seule t\u00e9l\u00e9commande, apr\u00e8s retour des utilisateurs. L\u2018approche marketing est originale pour faire un A\/B testing : ils diffusent les deux accessoires \u00e0 une masse critique de clients pour faire ensuite un \u00e9lagage de l\u2019offre. On esp\u00e8re que cela ne d\u00e9cevra pas 45% des minoritaires apr\u00e8s coup ! Mais ils pourraient toujours proposer en option celle qui n\u2019aura pas \u00e9t\u00e9 retenue.<\/p>\n<p><u>Commande vocale<\/u><\/p>\n<p>La box est pilotable par la voix avec l\u2019assistant maison \u201cOK Freebox\u201d qui est cens\u00e9 fonctionner sans passer par le cloud. Selon la tradition chez Free, il est probablement d\u00e9velopp\u00e9 avec des outils open source. Cela permet de g\u00e9rer l\u2019acc\u00e8s aux contenus et les les fonctionnalit\u00e9s du serveur et du player. Dans la d\u00e9monstration, cela permet d\u2019acc\u00e9der \u00e0 l\u2019offre de contenus contenant Jean Dujardin. Reste \u00e0 voir ce que cela va donner avec des noms d\u2019acteurs et de r\u00e9alisateurs polonais ou chinois !<\/p>\n<p>S\u2019y ajoute le support d\u2019Amazon Alexa qui servira surtout \u00e0 piloter les objets connect\u00e9s de la maison et des contenus autres que ceux qui sont propos\u00e9s par le biais de Free dans son Player. L\u00e0, on passe par le cloud.<\/p>\n<p>Ces deux commandes vocales utilisent 4 micros directionnels et s\u2019activent ou se d\u00e9sactivent avec un bouton au-dessus de la box. Cela rassurera les utilisateurs soucieux de la pr\u00e9servation de leur vie priv\u00e9e.<\/p>\n<p>La FreeBox Mini 4K tournait sous Android. La Delta n\u2019utilise pas Android et doit tourner sous une version de Linux compl\u00e9t\u00e9e de briques logicielles open source diverses pour la plupart et de code d\u00e9velopp\u00e9 par Free et par quelques partenaires. Exactement comme c\u2019\u00e9tait le cas dans la Freebox R\u00e9volution.<\/p>\n<p>Finalement, Free a remplac\u00e9 un GAFA par un autre dans l\u2019\u00e9quation. Google pour Amazon ! En ajoutant Netflix au passage. Mais Amazon n\u2019acc\u00e8dera pas \u00e0 nos habitudes de consommation de TV, ce qui est toujours \u00e7a de gagn\u00e9 c\u00f4t\u00e9 vie priv\u00e9e. Sauf s\u2019il \u00e9coute les cha\u00eenes que vous visionnez. On imagine que les \u00e9quipes de Free emp\u00eachent cela.<\/p>\n<p><u>QiPower<\/u><\/p>\n<p>Le Player comprend un syst\u00e8me de recharge au standard QiPower, utilis\u00e9 par la t\u00e9l\u00e9commande tactile. Il pourrait aussi servir \u00e0 recharger vos smartphones et autres appareils utilisant le standard Qi, sauf apparemment les iPhone r\u00e9cents.<\/p>\n<p><u>Connectique<\/u><\/p>\n<p>La connectique comprend notamment deux ports Gigabits. Il y a toujours une entr\u00e9e d\u2019antenne TNT. La box comprend aussi un port HDMI 2.1 alors qu\u2019il n\u2019est semble-t-il pas support\u00e9 par le processeur Qualcomm de la box. C\u2019est bizarre. Le chipset Snapdragon 835 supporte le HDMI jusqu\u2019au 2.0A.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image20.png\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image20_thumb.png\" alt=\"image\" width=\"298\" height=\"159\" border=\"0\" \/><\/a><\/p>\n<p><strong>Contenus<\/strong><\/p>\n<p>Free a \u00e9galement d\u00e9cid\u00e9 de mettre le paquet dans ce domaine.<\/p>\n<p>Cela commence avec l\u2019int\u00e9gration habituelle des cha\u00eenes de TV d\u2019un bouquet assez large, compl\u00e9t\u00e9 comme avant par celles de \u201cCanal Panorama\u201d, ex CanalSat, mais sans Canal+ et ses contenus premium. Ce sont les cha\u00eenes de documentaires, de voyages, de films de stock, etc.<\/p>\n<p>Le Player donne un acc\u00e8s \u00e0 600 cha\u00eenes TV dont plus d\u2019une centaine avec les contenus en replay, m\u00eame TF1 et M6, et deux qui sont diffus\u00e9es en 4K, Stingray Festival et Ultra Nature (<a href=\"https:\/\/www.free.fr\/data\/pdf\/freeboxtv.pdf\">liste compl\u00e8te<\/a>). Le Guide de Programme est toujours l\u00e0. Ouf. La majorit\u00e9 de ces cha\u00eenes sont disponibles en multi-\u00e9crans, sur smartphone, tablette et ordinateur.<\/p>\n<p>La grande nouveaut\u00e9 est l\u2019int\u00e9gration dans l\u2019abonnement des contenus de Netflix qui correspondent \u00e0 l\u2019abonnement de base de ce dernier \u00e0 7,90\u20ac. Il ne couvre qu\u2019un seul \u00e9cran et est en qualit\u00e9 SD. Un upgrade est possible \u00e0 partir de Free pour obtenir la version Standard (+3\u20acpar mois) et la version Premium (+6\u20ac par mois) pour la 4K et le support de quatre \u00e9crans. Si vous \u00eates d\u00e9j\u00e0 abonn\u00e9 \u00e0 Netflix, vous pourrez \u00e9conomiser l\u2019\u00e9quivalent de l\u2019abonnement de base de 7,9\u20ac dans votre abonnement Freebox Delta. Mais le \u201cplus\u201d Netflix n\u2019est pas en option pour les autres clients. C\u2019est un bundle <em>und\u00e9bundleisable<\/em> !<\/p>\n<p>L\u2019offre de Free comprend \u00e9galement 1000 titres de la presse \u00e9crite via LeKiosk et consultables sur tous types d\u2019\u00e9crans.<\/p>\n<p>Ajoutons-y le support logiciel de YouTube (y compris on l\u2019esp\u00e8re en 4K, vu que le Snapdragon 835 supporte le format VP9 utilis\u00e9 par YouTube pour la 4K), Spotify (musique), Qobuz (musique en format audio HiRes), Twitch (jeux vid\u00e9os) et autres Deezer (musique), mais pour lesquels il faut s\u2019abonner s\u00e9par\u00e9ment pour en profiter (hors YouTube).<\/p>\n<p>Bref, on peut y passer beaucoup de temps si l\u2019on n\u2019a rien d\u2019autre \u00e0 faire !<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Freebox-Delta-Replay.jpg\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"Freebox Delta Replay\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/Freebox-Delta-Replay_thumb.jpg\" alt=\"Freebox Delta Replay\" width=\"537\" height=\"304\" border=\"0\" \/><\/a><\/p>\n<p>Le tout s\u2019exploite avec une interface utilisateur revisit\u00e9e s\u2019inspirant de l\u2019\u00e9tat de l\u2019art actuel avec des barres de jaquettes qui d\u00e9filent horizontalement. Un moteur de recherche est capable de scanner tous les contenus disponibles ce qui n\u2019est pas une nouveaut\u00e9 march\u00e9 en soi mais aligne cette box sur le \u201cstate of the art\u201d des concurrents en France. Cette interface est tr\u00e8s fluide et b\u00e9n\u00e9ficie de la puissance du chipset Snapdragon 835.<\/p>\n<p>L\u2019int\u00e9gration de tous ces contenus dans l\u2019abonnement est un bon deal pour ceux qui appr\u00e9cient les contenus propos\u00e9s. Pour les autres, c\u2019est un peu de la vente forc\u00e9e comme le diraient les partisans du logiciel libre qui se battent contre Microsoft depuis 20 ans et les constructeurs qui imposent Windows aux acheteurs d\u2019ordinateurs personnels ! A ceci pr\u00e8s que Free n\u2019est ni monopolistique ni dominant dans ce march\u00e9 de la box o\u00f9 Orange est le leader.<\/p>\n<p>Cette int\u00e9gration traduit aussi la tendance d\u00e9flationniste constante de la valeur des contenus face \u00e0 l\u2019inflation c\u00f4t\u00e9 mat\u00e9riel. La vie num\u00e9rique est envahissante c\u00f4t\u00e9 temps pass\u00e9 mais elle co\u00fbte de moins en moins cher. Notre vie physique reste contrainte par les d\u00e9placements, le logement, l\u2019alimentation et l\u2019\u00e9quipement et peut avoir tendance \u00e0 co\u00fbter plus cher. Il para\u00eet !<\/p>\n<p><strong>Freebox One<\/strong><\/p>\n<p>La Freebox One devient l\u2019offre d\u2019entr\u00e9e de gamme de Free, amen\u00e9e \u00e0 remplacer la Freebox Mini 4K et la Crystal. Elle est consolid\u00e9e sur un seul boitier ce qui g\u00e9n\u00e8rera quelques contraintes d\u2019installation pour les utilisateurs pour qui l\u2019arriv\u00e9e de la fibre ou du cuivre n\u2019est pas \u00e0 proximit\u00e9 de la TV principale du logement.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image_4.png\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image_thumb_4.png\" alt=\"image\" width=\"385\" height=\"194\" border=\"0\" \/><\/a><\/p>\n<p>La Freebox One comprend deux chipsets, un Arm9 tournant \u00e0 1,2 Ghz avec 512 Go de m\u00e9moire pour la partie serveur, moins puissant que celui du serveur Freebox Delta et un Qualcomm Snapdragon APQ8098 identique \u00e0 celui du Player de la Freebox Delta, avec 2 Go de m\u00e9moire et 32 Go de stockage Flash pour la partie TV, ce qui est peu au regard du To de base du player de la Delta et des 256 Go de la Freebox R\u00e9volution. Il y a toute la connectique classique avec le support de la 4K en HDR10 et le HDMI 2.1 avec HDCP 2.2. Ce HDMI devrait d\u2019ailleurs \u00eatre plut\u00f4t du 2.0A d&#8217;apr\u00e8s les sp\u00e9cifications du Snapdragon 835 comme nous l&#8217;avons d\u00e9j\u00e0 vu pour le Delta Player.<\/p>\n<p>L\u2019interface utilisateur de la partie TV est la m\u00eame qu\u2019avec la Delta. Il lui manque la partie audio Devialet, le NAS \u00e0 plusieurs disques durs, tout comme le support du 10 Gbits\/s et l\u2019agr\u00e9gation DSL\/4G, ce qui est probablement regrettable pour la fameuse \u201cmamie du Cantal\u201d.<\/p>\n<p><a href=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image_5.png\"><img loading=\"lazy\" decoding=\"async\" style=\"background-image: none; padding-top: 0px; padding-left: 0px; display: inline; padding-right: 0px; border-width: 0px;\" title=\"image\" src=\"https:\/\/www.oezratty.net\/wordpress\/wp-content\/WindowsLiveWriter\/Les-symboliques-de-la-Freebox-7_2D\/image_thumb_5.png\" alt=\"image\" width=\"388\" height=\"195\" border=\"0\" \/><\/a><\/p>\n<p>La Freebox One est \u00e0 29,99\u20ac pendant 12 mois pour les 100 000 premiers abonn\u00e9s, puis \u00e0 39,99\u20ac pour les autres ou apr\u00e8s ces 12 mois.<\/p>\n<p>A noter que pour l&#8217;ensemble des offres Freebox fibre existantes et nouvelles, la vitesse d&#8217;upload maximale est pass\u00e9e \u00e0 400 Mbits\/s. C&#8217;est devenu op\u00e9rationnel chez les clients dans les jours qui ont suivi l&#8217;annonce du 4 d\u00e9cembre 2018.<\/p>\n<p><strong>Offres commerciales de la Freebox Delta<\/strong><\/p>\n<p>Avant, on avait tout compris avec Free. 29,99\u20ac et hop. Puis 39,99\u20ac. Maintenant, c\u2019est tout compris mais c\u2019est aussi tout compliqu\u00e9. Notamment pour comprendre la structure tarifaire.<\/p>\n<p>La Delta est propos\u00e9e \u00e0 49,99\u20ac par mois. Cela entra\u00eene une augmentation de 10\u20ac par rapport \u00e0 la Freebox R\u00e9volution qui absorbe pile poil le co\u00fbt d\u2019un abonnement Netflix \u00e0 7,9\u20ac par mois et celui d\u2019un abonnement \u00e0 LeKiosk \u00e0 2\u20ac par mois, qui est le prix propos\u00e9 chez un op\u00e9rateur t\u00e9l\u00e9com comme Bouygues Telecom depuis l\u2019\u00e9t\u00e9 2018. Il faut d\u2019ailleurs toujours distinguer le prix \u00e0 l\u2019unit\u00e9 (10\u20ac) et le prix de gros (2\u20ac). Sachant que le prix de Netflix pay\u00e9 par Free \u00e0 ce dernier a du \u00eatre n\u00e9goci\u00e9. Ce qui a donn\u00e9 une petite marge pour absorber le cout plus \u00e9lev\u00e9 de la box c\u00f4t\u00e9 serveur. Le co\u00fbt de la box c\u00f4t\u00e9 player est absorb\u00e9 totalement ou partiellement par sa vente.<\/p>\n<p>En effet, le player Delta est vendu aux clients pour 480\u20ac, qui peuvent \u00eatre pay\u00e9s en 1, 4, 24 ou 48 fois. Par exemple, avec 10\u20ac par mois sur 4 ans, ce qui nous met l\u2019abonnement \u00e0 la Delta \u00e0 59,99\u20ac.\u00a0 Il n\u2019est pour l\u2019instant pas possible de s\u2019en passer. Le Player appartient cependant au client tout comme le disque dur de 1 To du serveur, ce qui permet visiblement de faire des \u00e9conomies de taxes sur la copie priv\u00e9e. En th\u00e9orie donc, si on r\u00e9silie son abonnement apr\u00e8s avoir pay\u00e9 son player, on peut continuer \u00e0 en utiliser les services tiers comme\u00a0 YouTube, Dailymotion et m\u00eame Alexa. Mais \u00e9videmment, pas la partie IPTV.<\/p>\n<p>Comme on ne connait pas le co\u00fbt r\u00e9el du player, difficile de dire si Free le couvre avec son prix de vente ou le vend \u00e0 perte. S\u2019il couvre bien le prix, cette tarification permet probablement d\u2019amortir plus rapidement le co\u00fbt du mat\u00e9riel. Mais n\u2019oublions pas les deux t\u00e9l\u00e9commandes et le pack s\u00e9curit\u00e9 qui prennent probablement en partie la place du co\u00fbt de fabrication de la Freebox Revolution Server.<\/p>\n<p>Les frais de mise en service sont de 99\u20ac auxquels s\u2019ajoutent des frais de migration de 49\u20ac pour la Delta. Les abonn\u00e9s existants pourraient passer aux Freebox Delta et One en \u00e9conomisant ces 49\u20ac de frais de migration avec une anciennet\u00e9 de plus de 8 ans. Cette politique tarifaire est nouvelle et \u00e9videmment, contest\u00e9e.\u00a0Les r\u00e9actions n\u00e9gatives de certains freenautes ne se sont pas faites attendre (<a href=\"https:\/\/www.freenews.fr\/freenews-edition-nationale-299\/freebox-9\/freebox-delta-des-freenautes-fideles-expriment-leur-deception\">exemples<\/a>).<\/p>\n<p>Les offres existantes vont rapidement dispara\u00eetre (Freebox Mini 4K \u00e0 29,99\u20ac, Freebox Crystal et Freebox Revolution \u00e0 39,99\u20ac). Les abonn\u00e9s ayant d\u00e9j\u00e0 la fibre avec ces deux box verront cependant la vitesse d\u2019upload passer \u00e0 400 Mbits\/s. Ce qui les aligne avec les meilleures offres d\u2019Orange en place depuis quelques ann\u00e9es. Mais je n\u2019ai pas pu le constater pratiquement. Ce n\u2019est peut-\u00eatre qu\u2019une question de jour.<\/p>\n<p>Par contre, ce d\u00e9luge de fonctionnalit\u00e9 a une cons\u00e9quence : il faudra du temps pour tout dig\u00e9rer et configurer chez soi. On peut esp\u00e9rer que les tutoriels seront bien faits. Est-ce que tout cela va enrayer la perte d\u2019abonn\u00e9s fixe de Free, qui \u00e9tait de 60 000 sur un an, sans compter celle du mobile, situ\u00e9e aux alentours de 160 000 abonn\u00e9s et s\u2019explique par la qualit\u00e9 du r\u00e9seau semble-t-il moins bonne que celle des autres op\u00e9rateurs en France ? Difficile \u00e0 pr\u00e9voir.<\/p>\n<p>La Delta est ch\u00e8re puisqu\u2019elle fait passer un abonnement complet \u00e0 partir de la R\u00e9volution de 40\u20ac \u00e0 60\u20ac tout compris. Cela se justifie au minimum par les contenus (Netflix, LeKiosk) pour une moiti\u00e9 et pour le serveur et Devialet pour l\u2019autre moiti\u00e9. La partie kit de s\u00e9curit\u00e9 arrive en bonus. Il faut cependant faire confiance \u00e0 Free pour g\u00e9rer la centrale d\u2019alarme et le service d\u2019intervention sur site en cas d\u2019incident. Ce service propos\u00e9 \u00e0 2\u20ac\/mois comprenant deux interventions annuelles et 24h de gardiennage. C\u2019est \u00e9videmment bien moins que les services du march\u00e9 qui sont plut\u00f4t situ\u00e9s entre 30\u20ac et 40\u20ac par mois.<\/p>\n<p>De m\u00eame, l\u2019enceinte Devialet est int\u00e9ressante par la qualit\u00e9 du son g\u00e9n\u00e9r\u00e9 mais elle n\u2019int\u00e9ressera pas les clients qui n\u2019ont pas beaucoup de place sous leur TV, ceux qui sont d\u00e9j\u00e0 \u00e9quip\u00e9s d\u2019une belle barre de son ou d\u2019une installation home cin\u00e9ma. Free se d\u00e9fend en indiquant que tout l\u2019\u00e9quipement fourni repr\u00e9senterait l&#8217;\u00e9quivalent de 2000\u20ac d\u2019investissements. Sauf que nombre de ses clients ont d\u00e9j\u00e0 fait cette d\u00e9pense en pi\u00e8ces d\u00e9tach\u00e9es ! Donc, ils vont en fait payer cela deux fois ! Et il est difficile de d\u00e9bundler tout cela. On pourrait par exemple appr\u00e9cier un abonnement \u00e0 40\u20ac par mois sans le player et sans Netflix, LeKiosk et la centrale de s\u00e9curit\u00e9. Une sorte de dual-play.<\/p>\n<p>PS : le 12 d\u00e9cembre, Xavier Niel d\u00e9clarait dans une interview \u00e0 UniversFreebox avoir entendu ces diff\u00e9rentes critiques et annon\u00e7ait des \u00e9volutions des offres avec des frais de migration moins \u00e9lev\u00e9s, et gratuits pour les clients depuis au moins 5 ans, et la perspective d&#8217;un d\u00e9bundling du Player de l&#8217;offre Internet+Server (<a href=\"https:\/\/www.universfreebox.com\/article\/47677\/En-exclusivite-Xavier-Niel-prend-en-compte-les-mecontentements-autour-de-la-sortie-de-la-Freebox-Delta-et-corrige-le-tir\">source<\/a>). C&#8217;\u00e9tait confirm\u00e9 le 20 d\u00e9cembre 2018 avec l&#8217;annonce par Xavier Niel de Freebox Delta S, qui contient uniquement le serveur et sans le Player Devialet ni les offres de contenus associ\u00e9es, et pour 39,90\u20ac par mois. Bravo !<\/p>\n<p>La Freebox Delta compl\u00e8te devient en tout cas une v\u00e9ritable plateforme mat\u00e9rielle et de contenus. Cela traduit la volont\u00e9 farouche des op\u00e9rateurs t\u00e9l\u00e9coms de ne pas \u00eatre raval\u00e9s au r\u00f4le de simple fournisseur de tuyaux. D\u2019autres offres tierces vont \u00eatre annonc\u00e9es autour de ces nouvelles Freebox courant 2019. C\u2019est une v\u00e9ritable centrale de domotique pilot\u00e9e par la voix, qui supporte notamment les produits de Philips Hue et Somfy. On voit qu\u2019apr\u00e8s avoir h\u00e9sit\u00e9, Free s\u2019en engag\u00e9 plus r\u00e9solument dans l\u2019int\u00e9gration verticale et dans la maison connect\u00e9e. Les autres op\u00e9rateurs avaient d\u00e9j\u00e0 tent\u00e9 le coup et notamment SFR, mais avec la vente d\u2019options. Free n\u2019y est pas all\u00e9 de main morte et a mis en place une offre d\u2019embl\u00e9e plus compl\u00e8te. Un pari assez os\u00e9 qui rencontre des oppositions mais qui fera peut-\u00eatre rentrer, enfin, la domotique dans un grand nombre de foyers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s une longue attente, Free lan\u00e7ait enfin sa nouvelle g\u00e9n\u00e9ration de Freebox, les Delta et One, le 4 d\u00e9cembre 2018 (vid\u00e9o du lancement). La derni\u00e8re annonce datait de 2015 avec la Freebox Mini 4K. Du c\u00f4t\u00e9 des box haut de gamme, il fallait remonter \u00e0 d\u00e9cembre 2010 pour l\u2019annonce de la Freebox R\u00e9volution \u00ab V6 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,2659,32,2087,5,35],"tags":[872,3192,2822,129,829,404,3191,3190,407,130],"class_list":["post-16941","post","type-post","status-publish","format-standard","hentry","category-france","category-intelligence-artificielle","category-loisirs-numeriques","category-objets-connectes","category-technologie","category-video","tag-bouygues-telecom","tag-devialet","tag-dolby-atmos","tag-free","tag-freebox","tag-orange","tag-rj45","tag-sfp","tag-sfr","tag-xavier-niel"],"views":40824,"_links":{"self":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts\/16941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/comments?post=16941"}],"version-history":[{"count":0,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/posts\/16941\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/media?parent=16941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/categories?post=16941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oezratty.net\/wordpress\/wp-json\/wp\/v2\/tags?post=16941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}